{"id":9680,"date":"2026-04-09T19:28:37","date_gmt":"2026-04-09T19:28:37","guid":{"rendered":"https:\/\/www.band-maid.fr\/?page_id=9680"},"modified":"2026-04-24T12:06:40","modified_gmt":"2026-04-24T12:06:40","slug":"different-2","status":"publish","type":"page","link":"https:\/\/www.band-maid.fr\/index.php\/different-2\/","title":{"rendered":"Different"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"78\" src=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg\" alt=\"\" class=\"wp-image-8482\" srcset=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg 1024w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-300x23.jpg 300w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"BAND-MAID \/ Different (Official Music Video)\" width=\"950\" height=\"534\" src=\"https:\/\/www.youtube.com\/embed\/edlLhh8qVxM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"78\" src=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg\" alt=\"\" class=\"wp-image-8482\" srcset=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg 1024w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-300x23.jpg 300w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-advgb-columns advgb-columns-wrapper\" id=\"advgb-cols-09dd32d4-fe0d-4df8-84f0-921b14a095f8\"><div class=\"advgb-columns-container\"><div class=\"advgb-columns advgb-columns-row advgb-is-mobile advgb-columns-3 layout-13-13-13 mbl-layout-stacked vgutter-10\">\n<div class=\"wp-block-advgb-column advgb-column\" id=\"advgb-col-367f7e0e-8a59-4cc0-a567-4379edcfa393\"><div class=\"advgb-column-inner\" style=\"border-style:none;border-width:1px\">\n<p class=\"has-text-align-center\"><strong><a href=\"#Paroles\">Paroles officielles<\/a><\/strong><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-advgb-column advgb-column\" id=\"advgb-col-c3abbeeb-1fc5-4032-8c92-24db72df80c0\"><div class=\"advgb-column-inner\" style=\"border-style:none;border-width:1px\">\n<p class=\"has-text-align-center\"><strong><a href=\"#romanis\u00e9es\">Paroles romanis\u00e9es<\/a><\/strong><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-advgb-column advgb-column\" id=\"advgb-col-95cec89d-8c00-490c-920f-624735b097b4\"><div class=\"advgb-column-inner\" style=\"border-style:none;border-width:1px\">\n<p class=\"has-text-align-center\"><strong><a href=\"#fran\u00e7ais\">Paroles en fran\u00e7ais<\/a><\/strong><\/p>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Paroles\">Different<\/h2>\n\n\n\n<p>[Intro]<br>Let&rsquo;s go, it&rsquo;s showtime<\/p>\n\n\n\n<p>[Verse 1]<br>\u660f\u5929\u9ed2\u5730 \u7729\u3093\u3060\u5e38\u8ecc<br>Make it a rule \u8996\u754c\u306f\u75be\u8d70<br>Come back to, come back to, oh<br>Come back to, rise from the dead<\/p>\n\n\n\n<p>[Refrain]<br>\u5606\u304d\u7948\u3063\u3066\u3082\u884c\u304d\u6b62\u307e\u308a\u3060\u3063\u3066<br>\u795e\u3005\u3069\u3046\u304b? \u8ab0\u3082\u805e\u3044\u3061\u3083\u3044\u306a\u3044<br>\u76ee\u306b\u898b\u3048\u306a\u3044\u30e2\u30ce\u3058\u3083\u4fe1\u3058\u5f97\u306a\u3044<br>The clock is ticking<\/p>\n\n\n\n<p>[Pre-Chorus]<br>Once more \u7ff3\u308a\u3055\u3059\u52c7\u6c17<br>Once more \u8607\u308b\u30eb\u30fc\u30d7<br>No more \u3067\u3082\u307e\u3060\u3084\u3081\u306a\u3044<br>Just you wait<\/p>\n\n\n\n<p>[Chorus]<br>Totally different world<br>\u7121\u6c17\u529b\u306b\u711a\u304d\u4ed8\u3051\u3066\u5fc3\u6182\u3046<br>Awake your potential<br>\u6e26\u5dfb\u304f\u4e16\u754c\u306f<br>\u307e\u308b\u3067\u73fe\u5b9f\u306e\u3088\u3046\u306b<br>\u30d5\u30e9\u30c3\u30b7\u30e5\u3057\u3066\u63fa\u3089\u3044\u3067\u304f<br>Let&rsquo;s go, it&rsquo;s showtime<\/p>\n\n\n\n<p>[Verse 2]<br>\u7720\u308a\u306b\u3064\u304f\u307e\u3067 3\u79d2<br>\u3082\u3046\u4e00\u56de\u3063\u3066\u5e0c\u671b\u306f\u3069\u3053\u306b?<br>Come back to, come back to, oh<br>Come back to, rise from the dead<\/p>\n\n\n\n<p>[Refrain]<br>\u6d88\u3048\u3066\u304f\u9b42 \u80f8\u585e\u304c\u3063\u3066<br>\u5168\u3066\u306e\u7406\u89e3\u304c \u3053\u308c\u307e\u3067\u3068\u9055\u3046<br>\u30d5\u30a3\u30af\u30b7\u30e7\u30f3\u306b<br>\u55b0\u3089\u3044\u3064\u3051\u3088 \u30d5\u30a7\u30a4\u30af<br>Lost your bearings<\/p>\n\n\n\n<p>[Pre-Chorus]<br>Once more \u7e4b\u3044\u3067\u304f\u30ea\u30f3\u30b0<br>Once more \u98db\u3073\u8fbc\u3080\u8ff7\u5bae<br>No more \u307b\u3089\u307e\u3060\u3084\u308c\u308b<br>Just you wait<\/p>\n\n\n\n<p>[Chorus]<br>Totally different world<br>\u7121\u6c17\u529b\u306b \u711a\u304d\u4ed8\u3051\u3066 \u5fc3\u6182\u3046<br>Awake your potential<br>\u898b\u7d1b\u3046\u672a\u6765\u306f<br>\u307e\u308b\u3067\u7a7a\u865a\u3055\u3048\u3082\u5207\u308a\u88c2\u304f<br>\u30af\u30e9\u30c3\u30b7\u30e5\u3057\u3066\u5fae\u7b11\u3080<\/p>\n\n\n\n<p>[Bridge]<br>\u60aa\u9b54\u304b\u5929\u4f7f\u304b \u8868\u88cf\u306f\u4e00\u4f53<br>\u30ac\u30e9\u30af\u30bf\u306e\u4e2d\u3067\u8e0a\u308b\u3088 pa-pa-pa<br>\u9069\u5ea6\u306b\u9069\u5fdc?\u305d\u308c\u5fc5\u8981?<br>Nobody knows<br>One \u307e\u305f\u3069\u3053\u304b\u3067\u805e\u3053\u3048\u308bVoice<br>Two times \u672a\u6765\u304c\u904e\u53bb\u306b\u306a\u308b<br>\u7e70\u308a\u8fd4\u3057\u91cd\u306a\u3063\u3066<br>\u30b3\u30f3\u30c6\u30a3\u30cb\u30e5\u30fc? Start in my life<br>You can&rsquo;t back out now (Back out)<br>Deep in the dark, don&rsquo;t sink<\/p>\n\n\n\n<p>[Pre-Chorus]<br>Once more \u7ff3\u308a\u3055\u3059\u52c7\u6c17<br>Once more \u8607\u308b\u30eb\u30fc\u30d7<br>No more \u3067\u3082\u307e\u3060\u3084\u3081\u306a\u3044<br>Just you wait<\/p>\n\n\n\n<p>[Chorus]<br>Toally different world<br>\u7121\u6c17\u529b\u306b\u711a\u304d\u4ed8\u3051\u3066\u5fc3\u6182\u3046<br>Awake your potential<br>\u6e26\u5dfb\u304f\u4e16\u754c\u306f<br>\u307e\u308b\u3067\u73fe\u5b9f\u306e\u3088\u3046\u306b<br>\u30d5\u30e9\u30c3\u30b7\u30e5\u3057\u3066\u63fa\u3089\u3044\u3067\u304f<br>Let&rsquo;s go, it&rsquo;s showtime<\/p>\n\n\n\n<p>[Outro]<br>Your time to shine<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"78\" src=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg\" alt=\"\" class=\"wp-image-8482\" srcset=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg 1024w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-300x23.jpg 300w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"romanis\u00e9es\">Different (Paroles romanis\u00e9es)<\/h2>\n\n\n\n<p>[Intro]<br>Let&rsquo;s go, it&rsquo;s showtime<\/p>\n\n\n\n<p>[Verse 1]<br>Kontenkokuchi kuranda jouki<br>Make it a rule shikai wa shissou<br>Come back to, come back to, oh<br>Come back to, rise from the dead<\/p>\n\n\n\n<p>[Refrain]<br>Nageki inotte mo ikidomari datte<br>Kamigami douka? Dare mo kiicha inai<br>Menimienai mono ja shinji enai<br>The clock is ticking<\/p>\n\n\n\n<p>[Pre-Chorus]<br>Once more kageri sasu yuuki<br>Once more yomigaeru ruupu<br>No more demo mada yamenai<br>Just you wait<\/p>\n\n\n\n<p>[Chorus]<br>Totally different world<br>Mukiryoku ni takitsukete kokoro ureu<br>Awake your potential<br>Uzumaku sekai wa<br>Marude genjitsu no you ni<br>Furasshu shite yuraideku<br>Let&rsquo;s go, it&rsquo;s showtime<\/p>\n\n\n\n<p>[Verse 2]<br>Nemuri ni tsuku made san-byou<br>Mouikkai tte kibou wa dokoni?<br>Come back to, come back to, oh<br>Come back to, rise from the dead<\/p>\n\n\n\n<p>[Refrain]<br>Kieteku tamashii mune fusagatte<br>Subete no rikai ga kore made to chigau<br>Fikushon ni, kuraitsukeyo feiku<br>Lost your bearings<\/p>\n\n\n\n<p>[Pre-Chorus]<br>Once more tsunaide ku ringu<br>Once more tobikomu meikyuu<br>No more hora mada yareru<br>Just you wait<\/p>\n\n\n\n<p>[Chorus]<br>Totally different world<br>Mukiryoku ni takitsukete kokoro ureu<br>Awake your potential<br>Mimagau mirai wa<br>Marude kuukyo sae mo kirisaku<br>Kurasshu shite hohoemu<\/p>\n\n\n\n<p>[Bridge]<br>Akuma ka tenshi ka hyouri wa ittai<br>Garakuta no naka de odoru yo, pa-pa-pa<br>Tekido ni tekiou? Sore hitsuyou?<br>Nobody knows<br>One, mata doko ka de kikoeru voice<br>Two times, mirai ga kako ni naru<br>Kurikaeshi kasanatte<br>Kontinyuu? Start in my life<br>You can&rsquo;t back out now (Back out)<br>Deep in the dark, don&rsquo;t sink<\/p>\n\n\n\n<p>[Pre-Chorus]<br>Once more kageri sasu yuuki<br>Once more yomigaeru ruupu<br>No more demo mada yamenai<br>Just you wait<\/p>\n\n\n\n<p>[Chorus]<br>Totally different world<br>Mukiryoku ni takitsukete kokoro ureu<br>Awake your potential<br>Uzumaku sekai wa<br>Marude genjitsu no you ni<br>Furasshu shite yuraide ku<br>Let&rsquo;s go, it&rsquo;s showtime<\/p>\n\n\n\n<p>[Outro]<br>Your time to shine<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"78\" src=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg\" alt=\"\" class=\"wp-image-8482\" srcset=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg 1024w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-300x23.jpg 300w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"fran\u00e7ais\">Different (Paroles en fran\u00e7ais)<\/h2>\n\n\n\n<p>[Intro]<br>C&rsquo;est parti, que le spectacle commence<\/p>\n\n\n\n<p>[Couplet 1]<br>La nuit tombe, aucune lumi\u00e8re pour nous guider, l&rsquo;ordinaire semble \u00e9blouissant<br>Fais-en une r\u00e8gle, cours l\u00e0 o\u00f9 tu peux voir<br>Reviens, reviens, oh<br>Reviens, ressuscite<\/p>\n\n\n\n<p>[Refrain]<br>Le deuil et la pri\u00e8re ne m\u00e8nent nulle part<br>Et les dieux ? Personne n&rsquo;\u00e9coute<br>Difficile de croire en des existences que l&rsquo;on ne voit pas<br>Le temps passe<\/p>\n\n\n\n<p>[Pr\u00e9-refrain]<br>Une fois de plus, les ombres sapent mon courage<br>Une fois de plus, le cercle vicieux recommence<br>J&rsquo;en ai assez, mais je ne m&rsquo;arr\u00eaterai pas, pas encore<br>Attends un peu<\/p>\n\n\n\n<p>[Refrain]<br>Un monde totalement diff\u00e9rent<br>Une torche enflamm\u00e9e face \u00e0 mon apathie ; angoisse<br>R\u00e9veille ton potentiel<br>Ce monde qui s&rsquo;\u00e9croule<br>Scintille et s&rsquo;\u00e9loigne en vacillant<br>Comme si c&rsquo;\u00e9tait r\u00e9el<br>Allons-y, que le spectacle commence<\/p>\n\n\n\n<p>[Couplet 2]<br>Trois secondes avant de t&rsquo;endormir<br>Si tu pouvais avoir une derni\u00e8re chance, o\u00f9 irais-tu ?<br>Reviens, reviens, oh<br>Reviens, ressuscite d&rsquo;entre les morts<\/p>\n\n\n\n<p>[Refrain]<br>Mon \u00e2me se fl\u00e9trit, mon c\u0153ur s&rsquo;\u00e9touffe<br>Ma perception des choses a compl\u00e8tement chang\u00e9<br>Tout est devenu fiction<br>Croque-toi \u00e7a, imposteur<br>Tu as perdu tes rep\u00e8res<\/p>\n\n\n\n<p>[Pr\u00e9-refrain]<br>Une fois de plus, boucle le cercle ;<br>Une fois de plus, plonge dans le labyrinthe<br>C&rsquo;est fini, mais regarde, j&rsquo;en suis encore capable<br>Attends un peu<\/p>\n\n\n\n<p>[Refrain]<br>Un monde totalement diff\u00e9rent<br>Une torche enflamm\u00e9e face \u00e0 mon apathie ; angoisse<br>R\u00e9veille ton potentiel<br>Un avenir mal interpr\u00e9t\u00e9<br>Peut-il briser m\u00eame le vide<br>Tout s&rsquo;effondre, et tu peux sourire<\/p>\n\n\n\n<p>[Pont]<br>Diable ou ange, les deux faces d\u2019une m\u00eame m\u00e9daille<br>Dansant dans le d\u00e9sordre, pa-pa-pa<br>Des compromis confortables ? En as-tu besoin ?<br>Personne ne le sait<br>Une fois \u2014 encore une fois, quelque part, j\u2019entends une Voix<br>Deux fois \u2014 l\u2019avenir devient le pass\u00e9<br>Se r\u00e9p\u00e9tant, couche apr\u00e8s couche<br>Dois-je continuer ? Commencer ma vie<br>Tu ne peux plus faire marche arri\u00e8re maintenant (Marche arri\u00e8re)<br>Au plus profond de l&rsquo;obscurit\u00e9, ne sombre pas<\/p>\n\n\n\n<p>[Pr\u00e9-refrain]<br>Une fois de plus, les ombres \u00e9moussent mon courage ;<br>Une fois de plus, la boucle recommence<br>C&rsquo;est fini, mais je ne m&rsquo;arr\u00eaterai pas, pas encore<br>Attends un peu !<\/p>\n\n\n\n<p>[Refrain]<br>Un monde totalement diff\u00e9rent<br>Une torche enflamm\u00e9e face \u00e0 mon apathie ; angoisse<br>R\u00e9veille ton potentiel<br>Ce monde qui s&rsquo;\u00e9croule<br>Scintille et s&rsquo;\u00e9loigne en ondulant<br>Comme si c&rsquo;\u00e9tait r\u00e9el<br>C&rsquo;est parti, que le spectacle commence<\/p>\n\n\n\n<p>[Outro]<br>C&rsquo;est ton heure de briller<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"78\" src=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg\" alt=\"\" class=\"wp-image-8482\" srcset=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg 1024w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-300x23.jpg 300w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Paroles: <strong>Miku Kobato<\/strong><br>Musique: <strong>Band-Maid<\/strong><br>Single : <strong>Different<\/strong> (2 d\u00e9cembre 2020)<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"78\" src=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg\" alt=\"\" class=\"wp-image-8482\" srcset=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg 1024w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-300x23.jpg 300w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"notes-et-citations-bandmaid-songs-encyclopedia-cad0a177-9230-40aa-9c92-21fef39b499b\">Notes et citations (Band-Maid Songs Encyclopedia)<\/h2>\n\n\n\n<p>G\u00e9n\u00e9rique d&rsquo;ouverture de la s\u00e9rie anim\u00e9e \u00ab Log Horizon : Destruction of the Round Table \u00bb, diffus\u00e9e du 13 janvier 2021 au 31 mars 2021. Derni\u00e8re sortie chez Nippon Crown (Revolver Record)<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"78\" src=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg\" alt=\"\" class=\"wp-image-8482\" srcset=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg 1024w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-300x23.jpg 300w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>Miku Kobato<\/strong> : En fait, on l\u2019a \u00e9crite il y a longtemps, vers f\u00e9vrier de l\u2019ann\u00e9e derni\u00e8re [note : 2019], quand on a enregistr\u00e9 l\u2019album pr\u00e9c\u00e9dent, po. Ce n\u2019est donc pas comme si on l\u2019avait \u00e9crite dans ce contexte-l\u00e0, po. Cette chanson est termin\u00e9e depuis bien longtemps, po (rires). <\/p>\n\n\n\n<p><strong>\u25a0<\/strong> <strong>Oh, je ne m\u2019y attendais pas. Je pensais que c&rsquo;\u00e9tait une nouvelle \u00e9tape pour vous, car vous n&rsquo;aviez jamais eu de chanson en deux temps jusqu&rsquo;\u00e0 pr\u00e9sent (rires). <\/strong><br>M<strong>iku Kobato<\/strong> : (rires) Eh bien, c&rsquo;est vrai, on n&rsquo;avait jamais eu de chanson comme \u00e7a, et c&rsquo;est pour \u00e7a qu&rsquo;on ne l&rsquo;a pas incluse dans Conqueror, en se disant \u00ab Ce n&rsquo;est pas le bon moment pour\u2026 On s\u2019est dit que ce serait un bon choix pour un single ou pour le prochain album, parce que c\u2019est une bonne chanson, puis on a re\u00e7u la proposition de partenariat et on s\u2019est dit : \u00ab \u00c7a ira tr\u00e8s bien avec \u00bb. En fait, on avait pr\u00e9vu de la sortir plus t\u00f4t, mais \u00e7a a \u00e9t\u00e9 repouss\u00e9 \u00e0 cause du COVID, h\u00e9 h\u00e9 (rires). <\/p>\n\n\n\n<p><strong>\u25a0<\/strong> <strong>Je vois. Je comprends un peu pourquoi vous ne l\u2019avez pas incluse dans Conqueror. <\/strong><br><strong>Miku Kobato<\/strong> : Elle a un style diff\u00e9rent des autres chansons, donc \u00e7a ne nous semblait pas tout \u00e0 fait appropri\u00e9 de l&rsquo;inclure. Chez Band-Maid, on \u00e9crit pas mal de chansons, et on les garde souvent pour une prochaine fois ou on les met de c\u00f4t\u00e9 pour plus tard, comme Rinne (inclus dans Conqueror), po. [Remarque : Rinne \u00e9tait une chanson entra\u00eenante \u00e9crite \u00e0 l&rsquo;\u00e9poque de World Domination et qui a ensuite \u00e9t\u00e9 r\u00e9arrang\u00e9e en une chanson plus intense pour Conqueror.] On r\u00e9arrange des morceaux qu\u2019on a compos\u00e9s auparavant, et \u00ab Different \u00bb est l\u2019un d\u2019entre eux, po. <\/p>\n\n\n\n<p><strong>\u25a0<\/strong> <strong>Qu\u2019est-ce que tu t\u2019es dit quand Kanami-san t\u2019a fait \u00e9couter la d\u00e9mo ? <\/strong><br><strong>Miku Kobato<\/strong> : Je me suis dit : \u00ab Voil\u00e0 encore une chanson g\u00e9niale \u00bb, po. Du genre \u00ab C\u2019est encore compl\u00e8tement diff\u00e9rent ! \u00bb (rires) Quand on a fait Conqueror, il y avait beaucoup de chansons au tempo moyen, donc j\u2019ai \u00e9t\u00e9 surprise, po. La m\u00e9lodie \u00e9tait intense, alors je me suis dit que j\u2019aurais du mal \u00e0 \u00e9crire les paroles, po (rires). <\/p>\n\n\n\n<p><strong>\u25a0<\/strong> <strong>Band-Maid a beaucoup de morceaux rapides, mais n\u2019est-ce pas peut-\u00eatre votre morceau le plus rapide \u00e0 ce jour ?\u2026 <\/strong><br><strong>Miku Kobato<\/strong> : Oh, eh bien, il donne une impression de vitesse, mais ce n\u2019est pas le plus rapide, po. Pour l\u2019instant, le morceau le plus rapide, c\u2019est \u00ab Screaming \u00bb, po. [Remarque : \u00ab Screaming \u00bb est \u00e0 215 BPM, \u00ab Different \u00bb et \u00ab Dilemma \u00bb sont \u00e0 210 BPM.] Cette chanson est un peu dingue, po. On trouve toujours que c\u2019est trop, po (rires). La batterie est particuli\u00e8rement difficile, po. Je me dis toujours qu\u2019Ah-chan (Akane) doit \u00eatre crev\u00e9e, po (rires). C\u2019est l\u2019un de ses programmes d\u2019entra\u00eenement, po (rires).<\/p>\n\n\n\n<p><strong>\u25a0 C&rsquo;est donc comme \u00e7a que \u00e7a s&rsquo;est pass\u00e9. Avant d&rsquo;\u00e9crire \u00ab Different \u00bb, as-tu re\u00e7u des demandes de la part de l&rsquo;\u00e9quipe de production de l&rsquo;anime concernant le style musical ou les paroles ? <br>Kanami<\/strong> : Il n&rsquo;y a pas eu de demande. J&rsquo;en ai choisi une dans ma collection de d\u00e9mos et je l&rsquo;ai propos\u00e9e en disant : \u00ab Que diriez-vous d&rsquo;une chanson comme celle-ci ? \u00bb, et ils ont tout de suite r\u00e9pondu : \u00ab C&rsquo;est bien \u00bb, heureusement. Je me suis dit : \u00ab D&rsquo;accord, je vais l&rsquo;arranger pour qu&rsquo;elle corresponde \u00e0 l&rsquo;histoire et \u00e0 l&rsquo;ambiance de Log Horizon \u00bb, et je l&rsquo;ai finalis\u00e9e pour lui donner sa forme actuelle. <strong>Saiki<\/strong> : Mais tu as \u00e9chang\u00e9 plusieurs fois avec eux au sujet de la m\u00e9lodie, n\u2019est-ce pas ? <br><strong>Kanami<\/strong> : Oh, tu as raison. En r\u00e9ponse \u00e0 la premi\u00e8re m\u00e9lodie que j\u2019avais propos\u00e9e, ils voulaient que j\u2019en compose une avec une ambiance plus enjou\u00e9e et une autre avec un refrain plus accrocheur. J\u2019ai donc propos\u00e9 plusieurs variations, et l\u2019une d\u2019entre elles est devenue la m\u00e9lodie finale. <\/p>\n\n\n\n<p><strong>\u25a0<\/strong> <strong>J\u2019aimerais revenir un peu en arri\u00e8re. Quelle \u00e9tait ton id\u00e9e de d\u00e9part pour \u00e9crire \u00ab Different \u00bb ? <br>Kanami<\/strong> : \u00c0 l&rsquo;\u00e9poque o\u00f9 je l&rsquo;ai \u00e9crite, j&rsquo;\u00e9tais bloqu\u00e9e sur la composition des riffs. J&rsquo;en ai parl\u00e9 \u00e0 quelqu&rsquo;un, qui m&rsquo;a conseill\u00e9 de cr\u00e9er des riffs avec des cordes \u00e0 vide. J&rsquo;ai donc essay\u00e9 de composer ce genre de riffs, et c&rsquo;est ainsi qu&rsquo;est n\u00e9e \u00ab Different \u00bb. J\u2019ai ajout\u00e9 quelques triolets de noires pour donner plus de vitesse au riff. En composant Different de cette mani\u00e8re, j\u2019ai r\u00e9alis\u00e9 \u00e0 quel point les riffs sont importants, alors pendant le confinement, je suis devenue une v\u00e9ritable \u00ab machine \u00e0 riffs \u00bb (rires). <\/p>\n\n\n\n<p><strong>\u25a0<\/strong> <strong>J\u2019ai h\u00e2te d\u2019entendre tes futures chansons avec les riffs que tu as compos\u00e9s \u00e0 l\u2019\u00e9poque. Pourrais-tu nous parler aussi des<br>paroles de \u00ab Different \u00bb ? <\/strong><br><strong>Miku Kobato<\/strong>: On ne m\u2019avait pas non plus demand\u00e9 de th\u00e8me particulier pour les paroles, mais comme on nous avait propos\u00e9 d\u2019\u00e9crire un g\u00e9n\u00e9rique d\u2019ouverture, j\u2019ai voulu composer quelque chose que l\u2019on puisse appr\u00e9cier en regardant l\u2019anime, po. Tu sais, un anime et son g\u00e9n\u00e9rique d\u2019ouverture forment g\u00e9n\u00e9ralement un tout. Si le g\u00e9n\u00e9rique d&rsquo;ouverture est loin de l&rsquo;univers de l&rsquo;anime, \u00e7a g\u00e2chera le plaisir, et s&rsquo;il correspond parfaitement \u00e0 cet univers, \u00e7a doublera le plaisir. J&rsquo;ai donc lu le roman original dont s&rsquo;inspire l&rsquo;anime, et je me suis servi de \u00e7a pour d\u00e9velopper l&rsquo;univers, po. Le roman utilise beaucoup de mots forts\u2026 ou de mots originaux, et j&rsquo;ai int\u00e9gr\u00e9 cette touche dans les paroles pour que non seulement ceux qui regardent l&rsquo;anime, mais aussi ceux qui aiment le roman original puissent en profiter. <\/p>\n\n\n\n<p><strong>\u25a0<\/strong> T<strong>on sens aigu du choix des mots transpara\u00eet clairement dans les paroles de \u00ab Different \u00bb. En tant que g\u00e9n\u00e9rique d\u2019ouverture de Log<br>Horizon, les paroles nous font imaginer un monde diff\u00e9rent et des combats, mais tu n\u2019as pas utilis\u00e9 explicitement les mots \u00ab combat \u00bb ou \u00ab bataille \u00bb. <\/strong><br><strong>Miku Kobato<\/strong>: Exactement, po ! Si tu utilises le mot \u00ab bataille \u00bb, l\u2019image devient trop fixe, tu vois. Log Horizon est certes un anime de combat, mais les combats ne sont pas le seul centre d\u2019int\u00e9r\u00eat de son histoire. En plus de \u00e7a, je voulais \u00e9crire des paroles que chacun puisse appr\u00e9cier \u00e0 sa mani\u00e8re, po. Et puis, quand Kanami-chan m\u2019a envoy\u00e9 une d\u00e9mo de cette chanson, la m\u00e9lodie comportait tellement de notes. Je voulais en tirer le meilleur parti dans les paroles, alors je les ai \u00e9crites en me disant : \u00ab Sai-chan (Saiki) va s\u00fbrement avoir du mal, po \u00bb (rires). <br><strong>Saiki <\/strong>: Gr\u00e2ce \u00e0 \u00e7a, c\u2019\u00e9tait assez difficile de chanter cette chanson (rires). Le tempo est rapide, mais j\u2019ai trouv\u00e9 que la m\u00e9lodie ne correspondait pas tout \u00e0 fait au tempo. Cependant, je me suis dit que si Kanami-chan avait imagin\u00e9 une telle interpr\u00e9tation, je devais la suivre, et je l\u2019ai chant\u00e9e en studio en mettant l\u2019accent sur la fluidit\u00e9 de la prononciation. J\u2019ai modifi\u00e9 certains mots dans une partie o\u00f9 je n\u2019arrivais pas \u00e0 chanter facilement, malgr\u00e9 tous mes efforts, et j\u2019ai \u00e9galement harmonis\u00e9 mes parties avec celles de Kobato l\u00e0 o\u00f9 il y avait des interf\u00e9rences. <\/p>\n\n\n\n<p><strong>\u25a0<\/strong> <strong>La chanson allie puissance et splendeur, et la \u00ab tension \u00bb que tu cr\u00e9es dans la partie centrale est saisissante. <br>Saiki <\/strong>: C&rsquo;\u00e9tait la partie la plus difficile. <br><strong>Miku Kobato<\/strong> : Elle a dit qu&rsquo;elle \u00e9tait \u00e0 bout de souffle, po (rires). <br><strong>Saiki<\/strong> : Mais j\u2019ai pris suffisamment de temps pour enregistrer cette chanson, donc j\u2019ai l\u2019impression d\u2019avoir pu accorder plus d\u2019attention aux d\u00e9tails que d\u2019habitude. <br><strong>Miku Kobato<\/strong> : Les ch\u0153urs ont aussi \u00e9t\u00e9 difficiles, po. Dans la d\u00e9mo, Kanami-chan avait ajout\u00e9 plus de parties chant\u00e9es pour moi, Kobato. J\u2019ai d\u2019abord tout enregistr\u00e9, puis au mixage, j\u2019en ai supprim\u00e9 beaucoup pour que seules les meilleures parties restent, po. Cela dit, les passages les plus charg\u00e9s de cette chanson sont encore plus intenses qu\u2019avant. \u00c7a a \u00e9t\u00e9 difficile parce que les variations d\u2019intensit\u00e9 sont tr\u00e8s marqu\u00e9es et que la tessiture vocale est \u00e9galement tr\u00e8s large, po. <br><strong>Saiki <\/strong>: C\u2019est la premi\u00e8re chanson o\u00f9 tu as fait le \u00ab hairball \u00bb, n\u2019est-ce pas ? (rires). <br><strong>Miku Kobato<\/strong> : Exactement ! Je l\u2019ai essay\u00e9 pour la premi\u00e8re fois dans cette chanson, et j\u2019ai d\u00e9cid\u00e9 de d\u00e9velopper ce style de chant (rires). <\/p>\n\n\n\n<p><strong>\u25a0<\/strong> <strong>Ce que tu appelles \u00ab hairball \u00bb, c\u2019est la \u00ab voix d\u2019un chat qui recrache une boule de poils \u00bb dont tu parlais dans l\u2019interview de Conqueror, n\u2019est-ce pas ? <\/strong><br><strong>Miku Kobato<\/strong> : Oui (rires). Je ne l\u2019ai finalement pas gard\u00e9e pour Different, mais je l\u2019ai utilis\u00e9e dans l\u2019album \u00e0 la place (rires). <br><strong>Akane<\/strong> : Quand j\u2019ai \u00e9cout\u00e9 la d\u00e9mo de Different, la premi\u00e8re chose que je me suis dite, c\u2019est : \u00ab Voil\u00e0 une chanson enti\u00e8rement en deux temps. \u00bb C&rsquo;\u00e9tait la premi\u00e8re chanson \u00e0 deux temps du d\u00e9but \u00e0 la fin, alors que les chansons jusqu&rsquo;alors ne passaient souvent \u00e0 deux temps que dans les passages importants. De plus, le tempo est rapide, et le charleston r\u00e9sonne tout au long du morceau. En ce sens, ma formation de base s&rsquo;est av\u00e9r\u00e9e tr\u00e8s efficace. Je me concentrais sur l&rsquo;entra\u00eenement des doigts \u00e0 l&rsquo;\u00e9poque o\u00f9 j&rsquo;ai enregistr\u00e9 ce morceau, et ma m\u00e9thode consistant \u00e0 m&rsquo;habituer au tempo en bougeant les baguettes avec les doigts a donn\u00e9 d&rsquo;excellents r\u00e9sultats. De plus, je voulais avant tout faire ressortir la m\u00e9lodie, alors j&rsquo;ai consciemment essay\u00e9 de ne pas surcharger le morceau de sons. Les rythmes rapides \u00e0 deux temps ont tendance \u00e0 \u00eatre bruyants, j\u2019ai donc volontairement cr\u00e9\u00e9 une section simple pour souligner le changement, et je n\u2019ai jou\u00e9 de la grosse caisse qu\u2019une fois toutes les deux mesures. J\u2019ai longuement r\u00e9fl\u00e9chi \u00e0 la mani\u00e8re de rester simple tout en conservant la rapidit\u00e9\u2026 <br><strong>MISA<\/strong> : Pour la basse, c\u2019est un peu comme le dit Akane. Pour conserver cette impression de rapidit\u00e9, j\u2019ai essay\u00e9 de ne pas mettre trop de passages difficiles. \u00c0 la place, j\u2019ai jou\u00e9 des phrases qui mettent en valeur le picking et qui sonnent bien. Je voulais aussi que la basse soit rapide tout en ayant un sustain plus long. La batterie et les guitares sont tr\u00e8s pr\u00e9cises, alors je me suis dit que la<br>basse sonnerait mieux si je la jouais de cette fa\u00e7on. J\u2019ai donc essay\u00e9 de ne pas trop bouger ma main gauche tout en bougeant rapidement ma main droite tout au long du morceau, et j\u2019ai consciemment ajout\u00e9 une nuance de glissando. <\/p>\n\n\n\n<p><strong>\u25a0 Quand je t\u2019ai entendue jouer de la basse avec ce sustain \u00e0 ce tempo, je me suis dit : \u00ab C\u2019est tout \u00e0 fait toi, g\u00e9nial comme d\u2019habitude. \u00bb<\/strong><br><strong>MISA<\/strong> : Je m\u2019habitue sans doute \u00e0 cette vitesse. Comme on l\u2019a dit tout \u00e0 l\u2019heure, on a enregistr\u00e9 \u00ab Different \u00bb il y a environ un an,<br>tu sais. Du coup, je ne trouve pas \u00e7a particuli\u00e8rement rapide quand je le joue maintenant (rires). Je suis devenue une vraie bassiste depuis que j&rsquo;ai rejoint Band-Maid (rires). <br><strong>Kanami <\/strong>: J&rsquo;ai int\u00e9gr\u00e9 ma progression d&rsquo;accords pr\u00e9f\u00e9r\u00e9e. J&rsquo;ai toujours beaucoup aim\u00e9 les progressions avec des accords diminu\u00e9s, et j&rsquo;ai aussi \u00e9crit beaucoup de chansons avec des accords de tension comme ceux-l\u00e0 quand j&rsquo;\u00e9tais auteure-compositrice-interpr\u00e8te. Je me suis dit que ce serait le bon moment pour nous, Band-Maid, d&rsquo;utiliser une progression d&rsquo;accords de ce genre, qui d\u00e9gage une impression de solitude. La chanson est donc plus \u00e9labor\u00e9e au niveau des accords qu\u2019auparavant. Une autre particularit\u00e9, c\u2019est peut-\u00eatre que le solo de guitare n\u2019est pas du genre \u00ab \u00c9coutez ce solo ! \u00bb ; j\u2019en joue simplement un court en accompagnement du chant. C\u2019est parce que l\u2019image que j\u2019ai de l\u2019anime Log Horizon est un peu celle d\u2019un livre d\u2019images. Pour moi, \u00e7a ressemblait \u00e0 un livre d\u2019images un peu sombre, alors je me suis concentr\u00e9 sur l\u2019intrigue plut\u00f4t que sur l&rsquo;ambiance rock et j\u2019ai d\u00e9cid\u00e9 de ne pas inclure de solo qui sonne comme un solo de guitare classique.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"78\" src=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg\" alt=\"\" class=\"wp-image-8482\" srcset=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg 1024w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-300x23.jpg 300w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-advgb-columns advgb-columns-wrapper\" id=\"advgb-cols-82763417-2ce0-4c10-baa4-e3506a006285\"><div class=\"advgb-columns-container\"><div class=\"advgb-columns advgb-columns-row advgb-is-mobile advgb-columns-3 layout-13-13-13 mbl-layout-stacked vgutter-10\">\n<div class=\"wp-block-advgb-column advgb-column\" id=\"advgb-col-eeef3dab-3aa8-4f16-bb2e-1a0010e200a1\"><div class=\"advgb-column-inner\" style=\"border-style:none;border-width:1px\">\n<div class=\"wp-block-advgb-button align\"><a class=\"wp-block-advgb-button_link advgbbtn-d29f2e56-0a0f-47e6-a094-3f9753b5bd06\" href=\"https:\/\/www.band-maid.fr\/index.php\/different\/\" target=\"_self\" rel=\"noopener noreferrer\"><span>Single<\/span><\/a><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-advgb-column advgb-column\" id=\"advgb-col-765315b0-afc9-49b7-9efc-18298f6511b0\"><div class=\"advgb-column-inner\" style=\"border-style:none;border-width:1px\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-advgb-column advgb-column\" id=\"advgb-col-8a63720a-e47a-499d-b644-8698aa21d57f\"><div class=\"advgb-column-inner\" style=\"border-style:none;border-width:1px\">\n<div class=\"wp-block-advgb-button alignright\"><a class=\"wp-block-advgb-button_link advgbbtn-0ea8aa86-54a7-4766-8bf2-e3ff730eb664\" href=\"https:\/\/www.band-maid.fr\/index.php\/discographie-de-band-maid\/\" target=\"_self\" rel=\"noopener noreferrer\"><span>Discographie<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"78\" src=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg\" alt=\"\" class=\"wp-image-8482\" srcset=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg 1024w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-300x23.jpg 300w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n<style class=\"advgb-styles-renderer\">#advgb-col-367f7e0e-8a59-4cc0-a567-4379edcfa393>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-367f7e0e-8a59-4cc0-a567-4379edcfa393>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-367f7e0e-8a59-4cc0-a567-4379edcfa393>.advgb-column-inner{}}#advgb-col-c3abbeeb-1fc5-4032-8c92-24db72df80c0>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-c3abbeeb-1fc5-4032-8c92-24db72df80c0>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-c3abbeeb-1fc5-4032-8c92-24db72df80c0>.advgb-column-inner{}}#advgb-col-95cec89d-8c00-490c-920f-624735b097b4>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-95cec89d-8c00-490c-920f-624735b097b4>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-95cec89d-8c00-490c-920f-624735b097b4>.advgb-column-inner{}}#advgb-cols-09dd32d4-fe0d-4df8-84f0-921b14a095f8{}@media screen and (max-width: 1023px) {#advgb-cols-09dd32d4-fe0d-4df8-84f0-921b14a095f8{}}@media screen and (max-width: 767px) {#advgb-cols-09dd32d4-fe0d-4df8-84f0-921b14a095f8{}}#advgb-col-367f7e0e-8a59-4cc0-a567-4379edcfa393>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-367f7e0e-8a59-4cc0-a567-4379edcfa393>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-367f7e0e-8a59-4cc0-a567-4379edcfa393>.advgb-column-inner{}}#advgb-col-c3abbeeb-1fc5-4032-8c92-24db72df80c0>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-c3abbeeb-1fc5-4032-8c92-24db72df80c0>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-c3abbeeb-1fc5-4032-8c92-24db72df80c0>.advgb-column-inner{}}#advgb-col-95cec89d-8c00-490c-920f-624735b097b4>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-95cec89d-8c00-490c-920f-624735b097b4>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-95cec89d-8c00-490c-920f-624735b097b4>.advgb-column-inner{}}.advgbbtn-d29f2e56-0a0f-47e6-a094-3f9753b5bd06{font-size:18px;color:#fff !important;background-color:#2196f3 !important;margin:0px 0px 0px 0px !important;padding:10px 30px 10px 30px;border-width:1px !important;border-style:none;border-radius:50px !important;}.advgbbtn-d29f2e56-0a0f-47e6-a094-3f9753b5bd06:hover{box-shadow:1px 1px 12px 0px #ccc;opacity:1;transition:all 0.2s ease;}.advgbbtn-d29f2e56-0a0f-47e6-a094-3f9753b5bd06 > i {display: none !important;}#advgb-col-eeef3dab-3aa8-4f16-bb2e-1a0010e200a1>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-eeef3dab-3aa8-4f16-bb2e-1a0010e200a1>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-eeef3dab-3aa8-4f16-bb2e-1a0010e200a1>.advgb-column-inner{}}.advgbbtn-d29f2e56-0a0f-47e6-a094-3f9753b5bd06{font-size:18px;color:#fff !important;background-color:#2196f3 !important;margin:0px 0px 0px 0px !important;padding:10px 30px 10px 30px;border-width:1px !important;border-style:none;border-radius:50px !important;}.advgbbtn-d29f2e56-0a0f-47e6-a094-3f9753b5bd06:hover{box-shadow:1px 1px 12px 0px #ccc;opacity:1;transition:all 0.2s ease;}.advgbbtn-d29f2e56-0a0f-47e6-a094-3f9753b5bd06 > i {display: none !important;}#advgb-col-765315b0-afc9-49b7-9efc-18298f6511b0>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-765315b0-afc9-49b7-9efc-18298f6511b0>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-765315b0-afc9-49b7-9efc-18298f6511b0>.advgb-column-inner{}}.advgbbtn-0ea8aa86-54a7-4766-8bf2-e3ff730eb664{font-size:18px;color:#fff !important;background-color:#2196f3 !important;margin:0px 0px 0px 0px !important;padding:10px 30px 10px 30px;border-width:1px !important;border-style:none;border-radius:50px !important;}.advgbbtn-0ea8aa86-54a7-4766-8bf2-e3ff730eb664:hover{box-shadow:1px 1px 12px 0px #ccc;opacity:1;transition:all 0.2s ease;}.advgbbtn-0ea8aa86-54a7-4766-8bf2-e3ff730eb664 > i {display: none !important;}#advgb-col-8a63720a-e47a-499d-b644-8698aa21d57f>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-8a63720a-e47a-499d-b644-8698aa21d57f>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-8a63720a-e47a-499d-b644-8698aa21d57f>.advgb-column-inner{}}.advgbbtn-0ea8aa86-54a7-4766-8bf2-e3ff730eb664{font-size:18px;color:#fff !important;background-color:#2196f3 !important;margin:0px 0px 0px 0px !important;padding:10px 30px 10px 30px;border-width:1px !important;border-style:none;border-radius:50px !important;}.advgbbtn-0ea8aa86-54a7-4766-8bf2-e3ff730eb664:hover{box-shadow:1px 1px 12px 0px #ccc;opacity:1;transition:all 0.2s ease;}.advgbbtn-0ea8aa86-54a7-4766-8bf2-e3ff730eb664 > i {display: none !important;}#advgb-cols-82763417-2ce0-4c10-baa4-e3506a006285{}@media screen and (max-width: 1023px) {#advgb-cols-82763417-2ce0-4c10-baa4-e3506a006285{}}@media screen and (max-width: 767px) {#advgb-cols-82763417-2ce0-4c10-baa4-e3506a006285{}}#advgb-col-eeef3dab-3aa8-4f16-bb2e-1a0010e200a1>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-eeef3dab-3aa8-4f16-bb2e-1a0010e200a1>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-eeef3dab-3aa8-4f16-bb2e-1a0010e200a1>.advgb-column-inner{}}.advgbbtn-d29f2e56-0a0f-47e6-a094-3f9753b5bd06{font-size:18px;color:#fff !important;background-color:#2196f3 !important;margin:0px 0px 0px 0px !important;padding:10px 30px 10px 30px;border-width:1px !important;border-style:none;border-radius:50px !important;}.advgbbtn-d29f2e56-0a0f-47e6-a094-3f9753b5bd06:hover{box-shadow:1px 1px 12px 0px #ccc;opacity:1;transition:all 0.2s ease;}.advgbbtn-d29f2e56-0a0f-47e6-a094-3f9753b5bd06 > i {display: none !important;}#advgb-col-765315b0-afc9-49b7-9efc-18298f6511b0>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-765315b0-afc9-49b7-9efc-18298f6511b0>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-765315b0-afc9-49b7-9efc-18298f6511b0>.advgb-column-inner{}}#advgb-col-8a63720a-e47a-499d-b644-8698aa21d57f>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-8a63720a-e47a-499d-b644-8698aa21d57f>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-8a63720a-e47a-499d-b644-8698aa21d57f>.advgb-column-inner{}}.advgbbtn-0ea8aa86-54a7-4766-8bf2-e3ff730eb664{font-size:18px;color:#fff !important;background-color:#2196f3 !important;margin:0px 0px 0px 0px !important;padding:10px 30px 10px 30px;border-width:1px !important;border-style:none;border-radius:50px !important;}.advgbbtn-0ea8aa86-54a7-4766-8bf2-e3ff730eb664:hover{box-shadow:1px 1px 12px 0px #ccc;opacity:1;transition:all 0.2s ease;}.advgbbtn-0ea8aa86-54a7-4766-8bf2-e3ff730eb664 > i {display: none !important;}<\/style>","protected":false},"excerpt":{"rendered":"<p>Different [Intro]Let&rsquo;s go, it&rsquo;s showtime [Verse 1]\u660f\u5929\u9ed2\u5730 \u7729\u3093\u3060\u5e38\u8eccMake it a rule \u8996\u754c\u306f\u75be\u8d70Come back to, come back to, ohCome back to, rise from the dead [Refrain]\u5606\u304d\u7948\u3063\u3066\u3082\u884c\u304d\u6b62\u307e\u308a\u3060\u3063\u3066\u795e\u3005\u3069\u3046\u304b? \u8ab0\u3082\u805e\u3044\u3061\u3083\u3044\u306a\u3044\u76ee\u306b\u898b\u3048\u306a\u3044\u30e2\u30ce\u3058\u3083\u4fe1\u3058\u5f97\u306a\u3044The clock is ticking [Pre-Chorus]Once more \u7ff3\u308a\u3055\u3059\u52c7\u6c17Once more \u8607\u308b\u30eb\u30fc\u30d7No more \u3067\u3082\u307e\u3060\u3084\u3081\u306a\u3044Just you wait [Chorus]Totally different world\u7121\u6c17\u529b\u306b\u711a\u304d\u4ed8\u3051\u3066\u5fc3\u6182\u3046Awake your potential\u6e26\u5dfb\u304f\u4e16\u754c\u306f\u307e\u308b\u3067\u73fe\u5b9f\u306e\u3088\u3046\u306b\u30d5\u30e9\u30c3\u30b7\u30e5\u3057\u3066\u63fa\u3089\u3044\u3067\u304fLet&rsquo;s go, it&rsquo;s showtime [Verse 2]\u7720\u308a\u306b\u3064\u304f\u307e\u3067 3\u79d2\u3082\u3046\u4e00\u56de\u3063\u3066\u5e0c\u671b\u306f\u3069\u3053\u306b?Come back to, come back to, ohCome &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.band-maid.fr\/index.php\/different-2\/\" class=\"more-link\">Lire la suite de<span class=\"screen-reader-text\">\u00ab\u00a0Different\u00a0\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":9681,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"class_list":["post-9680","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Different - BAND-MAID<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.band-maid.fr\/index.php\/different-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Different - BAND-MAID\" \/>\n<meta property=\"og:description\" content=\"Different [Intro]Let&rsquo;s go, it&rsquo;s showtime [Verse 1]\u660f\u5929\u9ed2\u5730 \u7729\u3093\u3060\u5e38\u8eccMake it a rule \u8996\u754c\u306f\u75be\u8d70Come back to, come back to, ohCome back to, rise from the dead [Refrain]\u5606\u304d\u7948\u3063\u3066\u3082\u884c\u304d\u6b62\u307e\u308a\u3060\u3063\u3066\u795e\u3005\u3069\u3046\u304b? \u8ab0\u3082\u805e\u3044\u3061\u3083\u3044\u306a\u3044\u76ee\u306b\u898b\u3048\u306a\u3044\u30e2\u30ce\u3058\u3083\u4fe1\u3058\u5f97\u306a\u3044The clock is ticking [Pre-Chorus]Once more \u7ff3\u308a\u3055\u3059\u52c7\u6c17Once more \u8607\u308b\u30eb\u30fc\u30d7No more \u3067\u3082\u307e\u3060\u3084\u3081\u306a\u3044Just you wait [Chorus]Totally different world\u7121\u6c17\u529b\u306b\u711a\u304d\u4ed8\u3051\u3066\u5fc3\u6182\u3046Awake your potential\u6e26\u5dfb\u304f\u4e16\u754c\u306f\u307e\u308b\u3067\u73fe\u5b9f\u306e\u3088\u3046\u306b\u30d5\u30e9\u30c3\u30b7\u30e5\u3057\u3066\u63fa\u3089\u3044\u3067\u304fLet&rsquo;s go, it&rsquo;s showtime [Verse 2]\u7720\u308a\u306b\u3064\u304f\u307e\u3067 3\u79d2\u3082\u3046\u4e00\u56de\u3063\u3066\u5e0c\u671b\u306f\u3069\u3053\u306b?Come back to, come back to, ohCome &hellip; Lire la suite de\u00ab\u00a0Different\u00a0\u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.band-maid.fr\/index.php\/different-2\/\" \/>\n<meta property=\"og:site_name\" content=\"BAND-MAID\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bandmaid\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-24T12:06:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/Bandeau-different2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1190\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@bandmaid\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"17 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/index.php\\\/different-2\\\/\",\"url\":\"https:\\\/\\\/www.band-maid.fr\\\/index.php\\\/different-2\\\/\",\"name\":\"Different - BAND-MAID\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/index.php\\\/different-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/index.php\\\/different-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.band-maid.fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Bandeau-different2.jpg\",\"datePublished\":\"2026-04-09T19:28:37+00:00\",\"dateModified\":\"2026-04-24T12:06:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/index.php\\\/different-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.band-maid.fr\\\/index.php\\\/different-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/index.php\\\/different-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.band-maid.fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Bandeau-different2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.band-maid.fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Bandeau-different2.jpg\",\"width\":1200,\"height\":1190},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/index.php\\\/different-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.band-maid.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Different\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.band-maid.fr\\\/\",\"name\":\"BAND-MAID\",\"description\":\"WORLD DOMINATION\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.band-maid.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/#organization\",\"name\":\"BAND-MAID\",\"url\":\"https:\\\/\\\/www.band-maid.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/wglgkdc.cluster121.hosting.ovh.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logo_band-maid_b.png\",\"contentUrl\":\"http:\\\/\\\/wglgkdc.cluster121.hosting.ovh.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logo_band-maid_b.png\",\"width\":540,\"height\":93,\"caption\":\"BAND-MAID\"},\"image\":{\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/bandmaid\",\"https:\\\/\\\/x.com\\\/bandmaid\",\"https:\\\/\\\/www.instagram.com\\\/bandmaid.jp\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCJToUvYrmkmTCR-bluEaQfA\",\"https:\\\/\\\/www.tiktok.com\\\/@bandmaid_int\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Different - BAND-MAID","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.band-maid.fr\/index.php\/different-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Different - BAND-MAID","og_description":"Different [Intro]Let&rsquo;s go, it&rsquo;s showtime [Verse 1]\u660f\u5929\u9ed2\u5730 \u7729\u3093\u3060\u5e38\u8eccMake it a rule \u8996\u754c\u306f\u75be\u8d70Come back to, come back to, ohCome back to, rise from the dead [Refrain]\u5606\u304d\u7948\u3063\u3066\u3082\u884c\u304d\u6b62\u307e\u308a\u3060\u3063\u3066\u795e\u3005\u3069\u3046\u304b? \u8ab0\u3082\u805e\u3044\u3061\u3083\u3044\u306a\u3044\u76ee\u306b\u898b\u3048\u306a\u3044\u30e2\u30ce\u3058\u3083\u4fe1\u3058\u5f97\u306a\u3044The clock is ticking [Pre-Chorus]Once more \u7ff3\u308a\u3055\u3059\u52c7\u6c17Once more \u8607\u308b\u30eb\u30fc\u30d7No more \u3067\u3082\u307e\u3060\u3084\u3081\u306a\u3044Just you wait [Chorus]Totally different world\u7121\u6c17\u529b\u306b\u711a\u304d\u4ed8\u3051\u3066\u5fc3\u6182\u3046Awake your potential\u6e26\u5dfb\u304f\u4e16\u754c\u306f\u307e\u308b\u3067\u73fe\u5b9f\u306e\u3088\u3046\u306b\u30d5\u30e9\u30c3\u30b7\u30e5\u3057\u3066\u63fa\u3089\u3044\u3067\u304fLet&rsquo;s go, it&rsquo;s showtime [Verse 2]\u7720\u308a\u306b\u3064\u304f\u307e\u3067 3\u79d2\u3082\u3046\u4e00\u56de\u3063\u3066\u5e0c\u671b\u306f\u3069\u3053\u306b?Come back to, come back to, ohCome &hellip; Lire la suite de\u00ab\u00a0Different\u00a0\u00bb","og_url":"https:\/\/www.band-maid.fr\/index.php\/different-2\/","og_site_name":"BAND-MAID","article_publisher":"https:\/\/www.facebook.com\/bandmaid","article_modified_time":"2026-04-24T12:06:40+00:00","og_image":[{"width":1200,"height":1190,"url":"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/Bandeau-different2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@bandmaid","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"17 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.band-maid.fr\/index.php\/different-2\/","url":"https:\/\/www.band-maid.fr\/index.php\/different-2\/","name":"Different - BAND-MAID","isPartOf":{"@id":"https:\/\/www.band-maid.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.band-maid.fr\/index.php\/different-2\/#primaryimage"},"image":{"@id":"https:\/\/www.band-maid.fr\/index.php\/different-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/Bandeau-different2.jpg","datePublished":"2026-04-09T19:28:37+00:00","dateModified":"2026-04-24T12:06:40+00:00","breadcrumb":{"@id":"https:\/\/www.band-maid.fr\/index.php\/different-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.band-maid.fr\/index.php\/different-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.band-maid.fr\/index.php\/different-2\/#primaryimage","url":"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/Bandeau-different2.jpg","contentUrl":"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/Bandeau-different2.jpg","width":1200,"height":1190},{"@type":"BreadcrumbList","@id":"https:\/\/www.band-maid.fr\/index.php\/different-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.band-maid.fr\/"},{"@type":"ListItem","position":2,"name":"Different"}]},{"@type":"WebSite","@id":"https:\/\/www.band-maid.fr\/#website","url":"https:\/\/www.band-maid.fr\/","name":"BAND-MAID","description":"WORLD DOMINATION","publisher":{"@id":"https:\/\/www.band-maid.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.band-maid.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.band-maid.fr\/#organization","name":"BAND-MAID","url":"https:\/\/www.band-maid.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.band-maid.fr\/#\/schema\/logo\/image\/","url":"http:\/\/wglgkdc.cluster121.hosting.ovh.net\/wp-content\/uploads\/2026\/01\/logo_band-maid_b.png","contentUrl":"http:\/\/wglgkdc.cluster121.hosting.ovh.net\/wp-content\/uploads\/2026\/01\/logo_band-maid_b.png","width":540,"height":93,"caption":"BAND-MAID"},"image":{"@id":"https:\/\/www.band-maid.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bandmaid","https:\/\/x.com\/bandmaid","https:\/\/www.instagram.com\/bandmaid.jp\/","https:\/\/www.youtube.com\/channel\/UCJToUvYrmkmTCR-bluEaQfA","https:\/\/www.tiktok.com\/@bandmaid_int"]}]}},"coauthors":[],"author_meta":{"author_link":"https:\/\/www.band-maid.fr\/index.php\/author\/admin8693\/","display_name":"LJB"},"relative_dates":{"created":"Publi\u00e9 1 mois il y a","modified":"Mis \u00e0 jour 3 semaines il y a"},"absolute_dates":{"created":"Publi\u00e9 le 09\/04\/2026","modified":"Mise \u00e0 jour le 24\/04\/2026"},"absolute_dates_time":{"created":"Publi\u00e9 le 09\/04\/2026 19h28","modified":"Mise \u00e0 jour le 24\/04\/2026 12h06"},"featured_img_caption":"","featured_img":"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/Bandeau-different2.jpg","series_order":"","featured_media_urls":{"thumbnail":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/Bandeau-different2-150x150.jpg",150,150,true],"medium":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/Bandeau-different2-300x298.jpg",300,298,true],"medium_large":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/Bandeau-different2.jpg",768,762,false],"large":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/Bandeau-different2-1024x1015.jpg",950,942,true],"1536x1536":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/Bandeau-different2.jpg",1200,1190,false],"2048x2048":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/Bandeau-different2.jpg",1200,1190,false],"inspiro-featured-image":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/Bandeau-different2.jpg",1200,1190,false],"inspiro-loop":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/Bandeau-different2-950x320.jpg",950,320,true],"inspiro-loop@2x":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/Bandeau-different2-1200x640.jpg",1200,640,true],"portfolio_item-thumbnail":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/Bandeau-different2-600x400.jpg",600,400,true],"portfolio_item-thumbnail@2x":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/Bandeau-different2-1200x800.jpg",1200,800,true],"portfolio_item-masonry":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/Bandeau-different2-600x595.jpg",600,595,true],"portfolio_item-masonry@2x":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/Bandeau-different2.jpg",1200,1190,false],"portfolio_item-thumbnail_cinema":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/Bandeau-different2-800x335.jpg",800,335,true],"portfolio_item-thumbnail_portrait":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/Bandeau-different2-600x900.jpg",600,900,true],"portfolio_item-thumbnail_portrait@2x":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/Bandeau-different2.jpg",1200,1190,false],"portfolio_item-thumbnail_square":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/Bandeau-different2-800x800.jpg",800,800,true]},"_links":{"self":[{"href":"https:\/\/www.band-maid.fr\/index.php\/wp-json\/wp\/v2\/pages\/9680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.band-maid.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.band-maid.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.band-maid.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.band-maid.fr\/index.php\/wp-json\/wp\/v2\/comments?post=9680"}],"version-history":[{"count":3,"href":"https:\/\/www.band-maid.fr\/index.php\/wp-json\/wp\/v2\/pages\/9680\/revisions"}],"predecessor-version":[{"id":10081,"href":"https:\/\/www.band-maid.fr\/index.php\/wp-json\/wp\/v2\/pages\/9680\/revisions\/10081"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.band-maid.fr\/index.php\/wp-json\/wp\/v2\/media\/9681"}],"wp:attachment":[{"href":"https:\/\/www.band-maid.fr\/index.php\/wp-json\/wp\/v2\/media?parent=9680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}