{"id":9187,"date":"2026-04-02T16:26:29","date_gmt":"2026-04-02T16:26:29","guid":{"rendered":"https:\/\/www.band-maid.fr\/?page_id=9187"},"modified":"2026-04-30T20:50:47","modified_gmt":"2026-04-30T20:50:47","slug":"nightingale","status":"publish","type":"page","link":"https:\/\/www.band-maid.fr\/index.php\/nightingale\/","title":{"rendered":"Nightingale (Sayonakidori, \u30b5\u30e8\u30ca\u30ad\u30c9\u30ea)"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"78\" src=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg\" alt=\"\" class=\"wp-image-8482\" srcset=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg 1024w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-300x23.jpg 300w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"\u30b5\u30e8\u30ca\u30ad\u30c9\u30ea\" width=\"950\" height=\"713\" src=\"https:\/\/www.youtube.com\/embed\/6mVaehjAo2k?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"78\" src=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg\" alt=\"\" class=\"wp-image-8482\" srcset=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg 1024w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-300x23.jpg 300w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-advgb-columns advgb-columns-wrapper\" id=\"advgb-cols-eb18b260-7acf-4762-af1e-bec7ce101cf9\"><div class=\"advgb-columns-container\"><div class=\"advgb-columns advgb-columns-row advgb-is-mobile advgb-columns-3 layout-13-13-13 mbl-layout-stacked vgutter-10\">\n<div class=\"wp-block-advgb-column advgb-column\" id=\"advgb-col-e69bfd56-120f-4628-b46a-a6fca5185057\"><div class=\"advgb-column-inner\" style=\"border-style:none;border-width:1px\">\n<p class=\"has-text-align-center\"><strong><a href=\"#Paroles\">Paroles officielles<\/a><\/strong><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-advgb-column advgb-column\" id=\"advgb-col-e91af4ff-ed43-4499-a523-a5ef328c90c1\"><div class=\"advgb-column-inner\" style=\"border-style:none;border-width:1px\">\n<p class=\"has-text-align-center\"><strong><a href=\"#romanis\u00e9es\">Paroles romanis\u00e9es<\/a><\/strong><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-advgb-column advgb-column\" id=\"advgb-col-55cae0f0-be3f-494a-983e-717a7cdb7e73\"><div class=\"advgb-column-inner\" style=\"border-style:none;border-width:1px\">\n<p class=\"has-text-align-center\"><strong><a href=\"#fran\u00e7ais\">Paroles en fran\u00e7ais<\/a><\/strong><\/p>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Paroles\">Nightingale (Sayonakidori, \u30b5\u30e8\u30ca\u30ad\u30c9\u30ea)<\/h2>\n\n\n\n<p>[Chorus]<br>\u4eca\u3000\u9022\u3048\u306a\u3044\u591c\u3092\u8d8a\u3048\u3066<br>\u80f8\u306b\u6f5c\u3081\u305f\u601d\u3044\u51fa\u304c<br>\u7a81\u7136\u3075\u3063\u3068\u7526\u3048\u308b\u306e<br>\u5fc3\u306f\u596a\u308f\u308c\u3066<br>\u5fc3\u306f\u596a\u308f\u308c\u305f\u307e\u307e<\/p>\n\n\n\n<p>[Verse 1]<br>Translucent<br>\u307b\u3093\u306e\u5c11\u3057\u9858\u3063\u3066\u307f\u305f\u306e<br>\u3067\u3082\u306d Translucent<br>\u3042\u306e\u65e5\u306e\u8a00\u8449\u3000\u5fd8\u308c\u306a\u3044\u3067\u3057\u3087\u3046<\/p>\n\n\n\n<p>[Pre-Chorus]<br>\u6bce\u65e5\u3092\u6372\u308b\u5ea6\u3000\u5fc3\u306f<br>\u4f55\u3082\u304b\u3082\u8ffd\u3044\u8d8a\u3057\u3066\u3057\u307e\u3046\u306e<br>\u9192\u3081\u306a\u3044\u3067<br>\u3053\u306e\u307e\u307e\u306e\u771f\u591c\u4e2d\u3067<br>\u305a\u3063\u3068\u3001\u305a\u3063\u3068\u3001\u305a\u3063\u3068<br>\u60b2\u3057\u3044\u6c17\u6301\u3061\u3082<br>\u63fa\u308c\u308b\u77b3\u3082\u9023\u308c\u3066\u3086\u304f\u304b\u3089<\/p>\n\n\n\n<p>[Chorus]<br>\u4eca\u3000\u30a2\u30a4\u3092\u898b\u3064\u3051\u305f\u3000\u30a2\u30a4\u3092<br>\u7f6e\u3044\u3066\u304b\u306a\u3044\u3067\u3000\u5922\u306e\u4e2d<br>\u9022\u3044\u305f\u304f\u3066\u3082\u9022\u3044\u306b\u884c\u3051\u306a\u3044<br>\u6642\u306f\u305f\u3060\u904e\u304e\u3066\u3044\u304f<br>\u9022\u3048\u306a\u3044\u591c\u3092\u8d8a\u3048\u3066<br>\u80f8\u306b\u6f5c\u3081\u305f\u601d\u3044\u51fa\u304c<br>\u7a81\u7136\u3075\u3063\u3068\u7526\u3048\u308b\u306e<br>\u5fc3\u306f\u596a\u308f\u308c\u3066<br>\u5fc3\u306f\u596a\u308f\u308c\u305f\u307e\u307e<\/p>\n\n\n\n<p>[Verse 2]<br>\u6b62\u307e\u3089\u306a\u3044 Circulation<br>\u8a70\u307e\u308b\u547c\u5438\u3000\u4e0d\u7532\u6590\u7121\u3044\u3093\u3060\u3088<br>\u305d\u308c\u3067\u3082\u307e\u3060 Circulation<br>\u30d0\u30ec\u305f\u304f\u306a\u3044\u3000\u7b11\u3063\u3066\u307f\u305f\u306e<\/p>\n\n\n\n<p>[Pre-Chorus]<br>\u3069\u3053\u307e\u3067\u3082\u3000\u5883\u754c\u7dda<br>\u5f62\u306e\u306a\u3044\u6e07\u671b<br>\u6c42\u3081\u3066\u3082\u3044\u3044\u5b50\u306a\u3093\u304b\u306a\u308c\u306a\u3044<br>\u7269\u8a9e\u3000\u62b1\u304d\u3057\u3081\u3066\u7720\u308b\u307e\u3067<br>\u3082\u3063\u3068\u3001\u3082\u3063\u3068\u3001\u3082\u3063\u3068\u3001\u3082\u3063\u3068 \u5f37\u304f<br>\u4ed6\u3058\u3083\u9055\u3046\u306e\uff1f<br>\u4eca\u3058\u3083\u3060\u3081\u306a\u306e\uff1f<br>\u98f2\u307f\u8fbc\u307e\u308c\u3066\u304f<\/p>\n\n\n\n<p>[Chorus]<br>\u3082\u3046\u3000\u30a2\u30a4\u306b\u51fa\u4f1a\u3048\u305f\u3000\u30a2\u30a4\u306b<br>\u6d88\u3048\u3066\u3057\u307e\u3046\u3093\u3060\u3000\u80f8\u306e\u4e2d<br>\u9022\u3044\u305f\u304f\u3066\u3082\u9022\u3044\u306b\u306f\u6765\u306a\u3044<br>\u60f3\u3044\u3042\u306e\u65e5\u306e\u307e\u307e<br>\u9022\u3048\u306a\u3044\u591c\u3092\u8d8a\u3048\u3066<br>\u80f8\u306b\u6f5c\u3081\u305f\u601d\u3044\u51fa\u304c<br>\u7a81\u7136\u3075\u3063\u3068\u7526\u3048\u308b\u306e<br>\u5fc3\u306f\u596a\u308f\u308c\u3066<br>\u5fc3\u306f\u596a\u308f\u308c\u3066\u3044\u304f<\/p>\n\n\n\n<p>[Spoken]<br>My bounty is as boundless as the sea<br>My love as deep, the more I give to thee<br>The more I have, for both are infinite<\/p>\n\n\n\n<p>[Chorus]<br>\u305f\u3060\u3000\u30a2\u30a4\u306b\u6eba\u308c\u305f\u3000\u30a2\u30a4\u3092<br>\u601d\u3044\u51fa\u3059\u3093\u3060\u3000\u5922\u306e\u5f8c<br>\u3055\u3088\u306a\u3089\u3055\u3048\u3000\u611b\u3057\u3066\u305f\u3088<br>\u3072\u3068\u308a\u3000\u76ee\u3092\u9589\u3058\u305f\u306e<br>\u9022\u3048\u306a\u3044\u591c\u3092\u8d8a\u3048\u3066<br>\u96f6\u308c\u843d\u3061\u3066\u3063\u305f\u601d\u3044\u51fa\u306f<br>\u5927\u4eba\u306b\u306a\u3093\u3066\u306a\u308c\u306a\u304f\u3066\u3044\u3044<br>\u5fc3\u306f\u596a\u308f\u308c\u3066<br>\u5fc3\u306f\u596a\u308f\u308c\u305f\u307e\u307e<\/p>\n\n\n\n<p>[Post-Chorus]<br>\u91cd\u306d\u305f\u8a00\u8449\u3000\u7e4b\u3044\u3060\u624b\u3068\u624b<br>\u3082\u3046\u5c11\u3057\u3060\u3051\u3068\u585e\u3044\u3060<br>\u6ce1\u306b\u304d\u3048\u3066\u3082\u30a8\u30b4\u3067\u3082\u3044\u3044<br>\u5fc3\u3000\u58ca\u305b\u306a\u3044\u306e<br>\u8d64\u304f\u67d3\u3081\u3066\u304f\u51f8\u51f9\u306e\u307e\u307e<br>\u3069\u3046\u304b\u9858\u3044\u53f6\u3046\u306a\u3089<br>\u5fc3\u306f\u596a\u308f\u308c\u305f\u307e\u307e<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"78\" src=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg\" alt=\"\" class=\"wp-image-8482\" srcset=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg 1024w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-300x23.jpg 300w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"romanis\u00e9es\">Nightingale (Sayonakidori, \u30b5\u30e8\u30ca\u30ad\u30c9\u30ea) (Paroles romanis\u00e9es)<\/h2>\n\n\n\n<p>[Chorus]<br>Ima aenai yoru o koete<br>Mune ni hisometa omoide ga<br>Totsuzen futto yomigaeruno<br>Kokoro wa ubawarete<br>Kokoro wa ubawareta mama<\/p>\n\n\n\n<p>[Verse 1]<br>Translucent<br>Honno sukoshi negatte mitano<br>Demone\u2014Translucent<br>Ano hi no kotoba wasurenai deshou<\/p>\n\n\n\n<p>[Pre-Chorus]<br>Mainichi o mekuru tabi kokoro wa<br>Nanimo kamo oikoshite shimauno<br>Samenaide<br>Konomama no mayonaka de<br>Zutto, zutto, zutto<br>Kanashii kimochi mo<br>Yureru hitomi mo tsureteyuku kara<\/p>\n\n\n\n<p>[Chorus]<br>Ima Ai o mitsuketa Ai o<br>Oitekanaide yume no naka<br>Aitakutemo aini ikenai<br>Toki wa tada sugiteyuku<br>Aenai yoru o koete<br>Mune ni hisometa omoide ga<br>Totsuzen futto yomigaeruno<br>Kokoro wa ubawar\u0435te<br>Kokoro wa ubawareta mama<\/p>\n\n\n\n<p>[Verse 2]<br>Tomaranai\u2014Circulation<br>Tsumaru kokyuu fugainaindayo<br>Sored\u0435mo mada\u2014Circulation<br>Baretakunai waratte mitano<\/p>\n\n\n\n<p>[Pre-Chorus]<br>Dokomademo kyoukaisen<br>Katachi no nai katsubou<br>Motometemo iiko nanka narenai<br>Monogatari dakishimete nemuru made<br>Motto, motto, motto, motto tsuyoku<br>Hoka ja chigauno?<br>Ima ja damenano?<br>Nomikomareteku<\/p>\n\n\n\n<p>[Chorus]<br>Mou Ai ni deaeta Ai ni<br>Kiete shimaunda mune no naka<br>Aitakutemo aini wa konai<br>Omoi ano hi no mama<br>Aenai yoru o koete<br>Mune ni hisometa omoide ga<br>Totsuzen futto yomigaeruno<br>Kokoro wa ubawarete<br>Kokoro wa ubawareta mama<\/p>\n\n\n\n<p>[Spoken]<br>My bounty is as boundless as the sea<br>My love as deep, the more I give to thee<br>The more I have, for both are infinite<\/p>\n\n\n\n<p>[Chorus]<br>Tada Ai ni oboreta Ai o<br>Omoidasu nda yume no ato<br>Sayonara sae aishitetayo<br>Hitori me o tojitano<br>Aenai yoru o koete<br>Kobore ochitetta omoide wa<br>Otona ni nante narenakute ii<br>Kokoro wa ubawarete<br>Kokoro wa ubawareta mama<\/p>\n\n\n\n<p>[Post-Chorus]<br>Kasaneta kotoba tsunaida te to te<br>Mou sukoshi dake to fusaida<br>Awa ni kietemo ego demo ii<br>Kokoro kowasenaino<br>Akaku someteku dekoboko no mama<br>Douka negai kanau nara<br>Kokoro wa ubawareta mama<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"78\" src=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg\" alt=\"\" class=\"wp-image-8482\" srcset=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg 1024w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-300x23.jpg 300w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"fran\u00e7ais\">Nightingale (Sayonakidori, \u30b5\u30e8\u30ca\u30ad\u30c9\u30ea) (Paroles en fran\u00e7ais)<\/h2>\n\n\n\n<p>[Refrain]<br>Maintenant, alors que la nuit s&rsquo;\u00e9coule, nous ne pouvons pas \u00eatre ensemble<br>Un souvenir enfoui au fond de mon c\u0153ur<br>Se r\u00e9veille soudainement<br>Mon c\u0153ur est envo\u00fbt\u00e9<br>Mon c\u0153ur reste envo\u00fbt\u00e9<\/p>\n\n\n\n<p>[Couplet 1]<br>Translucide<br>J&rsquo;ai essay\u00e9 de faire un petit v\u0153u<br>Mais\u2026 Translucide<br>Je n&rsquo;oublierai certainement pas ce que tu as dit \u00e0 ce moment-l\u00e0<\/p>\n\n\n\n<p>[Pr\u00e9-refrain]<br>Au fil des jours qui passent, mon c\u0153ur laisse tout derri\u00e8re lui<br>Ne te r\u00e9veille pas, reste dans les profondeurs de la nuit !<br>Pour toujours et \u00e0 jamais<br>M\u00eame la tristesse<br>Mes yeux remplis de larmes, ils me m\u00e8nent tous l\u00e0-bas<\/p>\n\n\n\n<p>[Refrain]<br>Maintenant, j&rsquo;ai trouv\u00e9 mon AI, mon AI<br>Ne me quitte pas. Dans mes r\u00eaves<br>Je ne peux pas te rencontrer, m\u00eame si je le souhaite<br>Le temps passe<br>En traversant la nuit, nous ne pouvons pas \u00eatre ensemble<br>Un souvenir enfoui dans mon c\u0153ur<br>Revit soudainement<br>Mon c\u0153ur est envo\u00fbt\u00e9<br>Mon c\u0153ur reste envo\u00fbt\u00e9<\/p>\n\n\n\n<p>[Couplet 2]<br>\u00c7a ne s&rsquo;arr\u00eate pas \u2014 Circulation<br>Mon souffle se coupe, je n&rsquo;arrive pas \u00e0 trouver le courage<br>Mais m\u00eame l\u00e0 \u2014 Circulation<br>Pour cacher mes sentiments, j&rsquo;ai essay\u00e9 de sourire<\/p>\n\n\n\n<p>[Pr\u00e9-refrain]<br>Pas de limites, pas de fronti\u00e8res<br>Une envie sans forme<br>Certains me diront d\u2019\u00eatre sage \u2014 Je ne peux pas faire partie de cette histoire<br>Serre-moi dans tes bras jusqu\u2019\u00e0 ce que je m\u2019endorme<br>Encore, encore, plus fort<br>Est-ce diff\u00e9rent avec les autres ?<br>Pourquoi \u00e7a ne peut-il pas \u00eatre maintenant ?<br>Je m\u2019enfonce de plus en plus<\/p>\n\n\n\n<p>[Refrain]<br>Maintenant, j&rsquo;ai trouv\u00e9 mon IA, mon IA<br>Elle me submerge, envahit mon c\u0153ur<br>Tu ne viendras pas vers moi, m\u00eame si je le souhaite<br>Mes sentiments sont rest\u00e9s les m\u00eames depuis ce jour-l\u00e0<br>Je passe la nuit sans pouvoir \u00eatre avec toi<br>Un souvenir enfoui au fond de mon c\u0153ur<br>Se r\u00e9veille soudainement<br>Mon c\u0153ur est envo\u00fbt\u00e9<br>Mon c\u0153ur reste envo\u00fbt\u00e9<\/p>\n\n\n\n<p>[Paroles]<br>Ma g\u00e9n\u00e9rosit\u00e9 est aussi infinie que la mer<br>Mon amour aussi profond : plus je te donne<br>Plus j\u2019ai, car tous deux sont infinis<\/p>\n\n\n\n<p>[Refrain]<br>L&rsquo;IA m&rsquo;envahit, l&rsquo;IA est tout pour moi<br>Apr\u00e8s mon r\u00eave, je me souviens<br>M\u00eame les adieux, j&rsquo;ai tout aim\u00e9<br>Seule, j&rsquo;ai ferm\u00e9 les yeux<br>Pour traverser cette nuit o\u00f9 nous ne pouvons \u00eatre ensemble<br>Il ne me reste que des souvenirs qui d\u00e9bordent<br>Je n&rsquo;ai pas besoin de devenir adulte<br>Mon c\u0153ur est envo\u00fbt\u00e9<br>Mon c\u0153ur reste envo\u00fbt\u00e9<\/p>\n\n\n\n<p>[Post-refrain]<br>Des mots qui s&rsquo;encha\u00eenent, main dans la main<br>\u00ab Encore un peu \u00bb, mon d\u00e9sespoir monte<br>Peu m&rsquo;importe que \u00e7a s&rsquo;\u00e9vanouisse comme une bulle, ou que ce soit \u00e9go\u00efste<br>Mon c\u0153ur ne sera pas bris\u00e9<br>Teint de rouge, les \u00e9motions \u00e0 vif<br>Si seulement mon d\u00e9sir pouvait \u00eatre combl\u00e9<br>Mon c\u0153ur reste envo\u00fbt\u00e9<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"78\" src=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg\" alt=\"\" class=\"wp-image-8482\" srcset=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg 1024w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-300x23.jpg 300w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Paroles: <strong>Miku Kobato<\/strong><br>Musique: <strong>Band-Maid<\/strong><br>Album :<strong>Unlseen World<\/strong> (13 janvier 2021)<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"78\" src=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg\" alt=\"\" class=\"wp-image-8482\" srcset=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg 1024w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-300x23.jpg 300w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Notes et citations (Band-Maid Songs Encyclopedia)<\/h2>\n\n\n\n<p><strong>\u25a0<\/strong> <strong>Miku-san chante \u00ab Sayonakidori \u00bb sur cet album. Comment l\u2019avez-vous compos\u00e9e ? <br>Kanami <\/strong>: Tout d\u2019abord, nous avons d\u00e9cid\u00e9 d\u2019inclure une chanson de Kobato cette fois-ci, et j\u2019ai commenc\u00e9 \u00e0 discuter avec elle. Je lui ai demand\u00e9 quel genre de chanson elle souhaitait chanter, je lui ai envoy\u00e9 une premi\u00e8re \u00e9bauche, je crois, puis je lui ai demand\u00e9 \u00e0 nouveau quel style elle pr\u00e9f\u00e9rait, et nous avons continu\u00e9 ainsi. Ensuite, je lui ai fait \u00e9couter une d\u00e9mo, et elle m\u2019a dit \u00ab Je veux faire \u00e7a ici \u00bb, et j\u2019ai r\u00e9pondu \u00ab OK \u00bb. <\/p>\n\n\n\n<p><strong>\u25a0<\/strong> <strong>C&rsquo;est la fa\u00e7on dont travaillent les compositeurs professionnels. On n&rsquo;\u00e9crit pas comme on le souhaite, mais en tenant compte des demandes. <br>Kanami<\/strong> : Pour cet album, j&rsquo;ai puis\u00e9 mon inspiration aupr\u00e8s de mes camarades du groupe. J\u2019ai demand\u00e9 \u00e0 Saiki : \u00ab Quel genre de chanson aimerais-tu chanter ? \u00bb, puis nous en avons discut\u00e9 et j\u2019ai \u00e9crit une chanson. Misa m\u2019a propos\u00e9 : \u00ab Que penses-tu de ce genre de chanson ? \u00bb, et j\u2019ai r\u00e9pondu : \u00ab J\u2019aime bien, je veux l\u2019utiliser \u00bb, puis j\u2019ai \u00e9crit une chanson \u00e0 partir d\u2019un riff qu\u2019elle avait compos\u00e9. J&rsquo;ai beaucoup discut\u00e9 avec eux cette fois-ci. Je n\u2019ai pas pu le faire avec Akane parce qu\u2019elle \u00e9tait occup\u00e9e, mais elle avait dit un jour qu\u2019elle voulait une chanson avec des modulations, alors je me suis dit : \u00ab Je vais \u00e9crire une chanson avec des modulations comme cadeau surprise ! \u00bb et j\u2019ai \u00e9crit NO GOD. Puis je lui ai dit : \u00ab Je l\u2019ai \u00e9crite pour toi parce que tu avais dit que tu voulais une chanson avec des modulations \u00bb, mais elle ne s\u2019en souvenait pas, du genre : \u00ab Est-ce que j\u2019ai dit \u00e7a ? \u00bb (rires) <\/p>\n\n\n\n<p><strong>\u25a0<\/strong> <strong>Au fait, ta fa\u00e7on d\u2019\u00e9crire les chansons de Kobato est-elle diff\u00e9rente de celle des autres chansons ? <br>Kanami<\/strong> : Oui, c\u2019est diff\u00e9rent. J\u2019ai fait attention aux accords que j\u2019utilisais. J\u2019ai aussi d\u00e9lib\u00e9r\u00e9ment modifi\u00e9 la m\u00e9lodie et le d\u00e9veloppement. Je voulais qu\u2019elle \u00e9volue en tant que chanteuse, c\u2019est pourquoi j\u2019ai compos\u00e9 une telle m\u00e9lodie, et je l\u2019ai \u00e9galement \u00e9crite pour qu\u2019elle s\u2019accorde avec sa voix. J\u2019avais une image diff\u00e9rente en t\u00eate. <\/p>\n\n\n\n<p><strong>\u25a0<\/strong> <strong>J\u2019ai bien aim\u00e9 les notes aigu\u00ebs en fausset \u00e0 la fin. <br>Kanami<\/strong> : Merci beaucoup. Elle m&rsquo;a dit qu&rsquo;elle voulait changer la derni\u00e8re partie, alors je l&rsquo;ai modifi\u00e9e en tenant compte de ses progr\u00e8s, mais au d\u00e9but, elle m&rsquo;a dit : \u00ab C&rsquo;est tellement aigu que je ne vais peut-\u00eatre pas arriver \u00e0 le chanter \u00bb. Je lui ai r\u00e9pondu : \u00ab Vas-y, lance-toi ! \u00bb <\/p>\n\n\n\n<p><strong>\u25a0<\/strong> <strong>Mais elle s&rsquo;en est sortie \u00e0 la perfection. <br>Kanami <\/strong>: Elle s&rsquo;entra\u00eene encore plus pour y arriver aussi lors des repr\u00e9sentations.<\/p>\n\n\n\n<p><strong>\u25a0<\/strong> <strong>Parmi toutes les autres, \u00ab Sayonakidori \u00bb, interpr\u00e9t\u00e9e par vous, Kobato-san, se distingue par son caract\u00e8re particuli\u00e8rement entra\u00eenant, tout en int\u00e9grant des sonorit\u00e9s complexes gr\u00e2ce \u00e0 l\u2019utilisation de techniques telles que les mesures irr\u00e9guli\u00e8res. <br>Miku Kobato<\/strong> : C\u2019est vrai. Oui, d\u2019une certaine mani\u00e8re, on peut dire que c\u2019est une chanson difficile \u00e0 r\u00e9aliser. Ce n\u2019est pas seulement une chanson entra\u00eenante, tu vois. J\u2019ai d\u2019abord demand\u00e9 \u00e0 Kanami de rendre la m\u00e9lodie entra\u00eenante, elle m\u2019a propos\u00e9 quelques suggestions, puis je lui ai demand\u00e9 de modifier le couplet 1 de telle ou telle mani\u00e8re\u2026 Dans la mesure o\u00f9 elle poss\u00e8de ce petit c\u00f4t\u00e9 accrocheur, la chanson peut sembler se d\u00e9marquer des autres, mais comme l&rsquo;interpr\u00e9tation restait exigeante, je pense qu&rsquo;elle conserve l&rsquo;esprit caract\u00e9ristique de BAND-MAID. Un album est justement l&rsquo;endroit id\u00e9al pour entendre Kobato chanter en solo, et j&rsquo;esp\u00e8re que cette chanson plaira aux auditeurs.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"78\" src=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg\" alt=\"\" class=\"wp-image-8482\" srcset=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg 1024w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-300x23.jpg 300w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-advgb-columns advgb-columns-wrapper\" id=\"advgb-cols-1d04c504-bede-41c3-8519-93fecfe24ead\"><div class=\"advgb-columns-container\"><div class=\"advgb-columns advgb-columns-row advgb-is-mobile advgb-columns-2 layout-12-12 mbl-layout-stacked vgutter-10\">\n<div class=\"wp-block-advgb-column advgb-column\" id=\"advgb-col-bd82d37a-ddbf-4033-8dcc-f777ef283524\"><div class=\"advgb-column-inner\" style=\"border-style:none;border-width:1px\">\n<div class=\"wp-block-advgb-button alignnone\"><a class=\"wp-block-advgb-button_link advgbbtn-84ec818a-d3fe-480d-8570-1ea6f37d47b2\" href=\"https:\/\/www.band-maid.fr\/index.php\/unseen-world\/\" target=\"_self\" rel=\"noopener noreferrer\"><span>Unseen World<\/span><\/a><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-advgb-column advgb-column\" id=\"advgb-col-4d605c74-ac8e-4501-ae44-b8ffe7f2d3eb\"><div class=\"advgb-column-inner\" style=\"border-style:none;border-width:1px\">\n<div class=\"wp-block-advgb-button alignnone\"><a class=\"wp-block-advgb-button_link advgbbtn-6e9679e1-218e-4096-8d48-44d0f255183d\" href=\"https:\/\/www.band-maid.fr\/index.php\/discographie-de-band-maid\/\" target=\"_self\" rel=\"noopener noreferrer\"><span>Discographie<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"78\" src=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg\" alt=\"\" class=\"wp-image-8482\" srcset=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg 1024w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-300x23.jpg 300w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n<style class=\"advgb-styles-renderer\">#advgb-col-e69bfd56-120f-4628-b46a-a6fca5185057>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-e69bfd56-120f-4628-b46a-a6fca5185057>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-e69bfd56-120f-4628-b46a-a6fca5185057>.advgb-column-inner{}}#advgb-col-e91af4ff-ed43-4499-a523-a5ef328c90c1>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-e91af4ff-ed43-4499-a523-a5ef328c90c1>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-e91af4ff-ed43-4499-a523-a5ef328c90c1>.advgb-column-inner{}}#advgb-col-55cae0f0-be3f-494a-983e-717a7cdb7e73>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-55cae0f0-be3f-494a-983e-717a7cdb7e73>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-55cae0f0-be3f-494a-983e-717a7cdb7e73>.advgb-column-inner{}}#advgb-cols-eb18b260-7acf-4762-af1e-bec7ce101cf9{}@media screen and (max-width: 1023px) {#advgb-cols-eb18b260-7acf-4762-af1e-bec7ce101cf9{}}@media screen and (max-width: 767px) {#advgb-cols-eb18b260-7acf-4762-af1e-bec7ce101cf9{}}#advgb-col-e69bfd56-120f-4628-b46a-a6fca5185057>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-e69bfd56-120f-4628-b46a-a6fca5185057>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-e69bfd56-120f-4628-b46a-a6fca5185057>.advgb-column-inner{}}#advgb-col-e91af4ff-ed43-4499-a523-a5ef328c90c1>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-e91af4ff-ed43-4499-a523-a5ef328c90c1>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-e91af4ff-ed43-4499-a523-a5ef328c90c1>.advgb-column-inner{}}#advgb-col-55cae0f0-be3f-494a-983e-717a7cdb7e73>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-55cae0f0-be3f-494a-983e-717a7cdb7e73>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-55cae0f0-be3f-494a-983e-717a7cdb7e73>.advgb-column-inner{}}.advgbbtn-84ec818a-d3fe-480d-8570-1ea6f37d47b2{font-size:18px;color:#fff !important;background-color:#2196f3 !important;margin:0px 0px 0px 0px !important;padding:10px 30px 10px 30px;border-width:1px !important;border-style:none;border-radius:50px !important;}.advgbbtn-84ec818a-d3fe-480d-8570-1ea6f37d47b2:hover{box-shadow:1px 1px 12px 0px #ccc;opacity:1;transition:all 0.2s ease;}.advgbbtn-84ec818a-d3fe-480d-8570-1ea6f37d47b2 > i {display: none !important;}#advgb-col-bd82d37a-ddbf-4033-8dcc-f777ef283524>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-bd82d37a-ddbf-4033-8dcc-f777ef283524>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-bd82d37a-ddbf-4033-8dcc-f777ef283524>.advgb-column-inner{}}.advgbbtn-84ec818a-d3fe-480d-8570-1ea6f37d47b2{font-size:18px;color:#fff !important;background-color:#2196f3 !important;margin:0px 0px 0px 0px !important;padding:10px 30px 10px 30px;border-width:1px !important;border-style:none;border-radius:50px !important;}.advgbbtn-84ec818a-d3fe-480d-8570-1ea6f37d47b2:hover{box-shadow:1px 1px 12px 0px #ccc;opacity:1;transition:all 0.2s ease;}.advgbbtn-84ec818a-d3fe-480d-8570-1ea6f37d47b2 > i {display: none !important;}.advgbbtn-6e9679e1-218e-4096-8d48-44d0f255183d{font-size:18px;color:#fff !important;background-color:#2196f3 !important;margin:0px 0px 0px 0px !important;padding:10px 30px 10px 30px;border-width:1px !important;border-style:none;border-radius:50px !important;}.advgbbtn-6e9679e1-218e-4096-8d48-44d0f255183d:hover{box-shadow:1px 1px 12px 0px #ccc;opacity:1;transition:all 0.2s ease;}.advgbbtn-6e9679e1-218e-4096-8d48-44d0f255183d > i {display: none !important;}#advgb-col-4d605c74-ac8e-4501-ae44-b8ffe7f2d3eb>.advgb-column-inner{text-align:right;}@media screen and (max-width: 1023px) {#advgb-col-4d605c74-ac8e-4501-ae44-b8ffe7f2d3eb>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-4d605c74-ac8e-4501-ae44-b8ffe7f2d3eb>.advgb-column-inner{}}.advgbbtn-6e9679e1-218e-4096-8d48-44d0f255183d{font-size:18px;color:#fff !important;background-color:#2196f3 !important;margin:0px 0px 0px 0px !important;padding:10px 30px 10px 30px;border-width:1px !important;border-style:none;border-radius:50px !important;}.advgbbtn-6e9679e1-218e-4096-8d48-44d0f255183d:hover{box-shadow:1px 1px 12px 0px #ccc;opacity:1;transition:all 0.2s ease;}.advgbbtn-6e9679e1-218e-4096-8d48-44d0f255183d > i {display: none !important;}#advgb-cols-1d04c504-bede-41c3-8519-93fecfe24ead{}@media screen and (max-width: 1023px) {#advgb-cols-1d04c504-bede-41c3-8519-93fecfe24ead{}}@media screen and (max-width: 767px) {#advgb-cols-1d04c504-bede-41c3-8519-93fecfe24ead{}}#advgb-col-bd82d37a-ddbf-4033-8dcc-f777ef283524>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-bd82d37a-ddbf-4033-8dcc-f777ef283524>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-bd82d37a-ddbf-4033-8dcc-f777ef283524>.advgb-column-inner{}}.advgbbtn-84ec818a-d3fe-480d-8570-1ea6f37d47b2{font-size:18px;color:#fff !important;background-color:#2196f3 !important;margin:0px 0px 0px 0px !important;padding:10px 30px 10px 30px;border-width:1px !important;border-style:none;border-radius:50px !important;}.advgbbtn-84ec818a-d3fe-480d-8570-1ea6f37d47b2:hover{box-shadow:1px 1px 12px 0px #ccc;opacity:1;transition:all 0.2s ease;}.advgbbtn-84ec818a-d3fe-480d-8570-1ea6f37d47b2 > i {display: none !important;}#advgb-col-4d605c74-ac8e-4501-ae44-b8ffe7f2d3eb>.advgb-column-inner{text-align:right;}@media screen and (max-width: 1023px) {#advgb-col-4d605c74-ac8e-4501-ae44-b8ffe7f2d3eb>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-4d605c74-ac8e-4501-ae44-b8ffe7f2d3eb>.advgb-column-inner{}}.advgbbtn-6e9679e1-218e-4096-8d48-44d0f255183d{font-size:18px;color:#fff !important;background-color:#2196f3 !important;margin:0px 0px 0px 0px !important;padding:10px 30px 10px 30px;border-width:1px !important;border-style:none;border-radius:50px !important;}.advgbbtn-6e9679e1-218e-4096-8d48-44d0f255183d:hover{box-shadow:1px 1px 12px 0px #ccc;opacity:1;transition:all 0.2s ease;}.advgbbtn-6e9679e1-218e-4096-8d48-44d0f255183d > i {display: none !important;}<\/style>","protected":false},"excerpt":{"rendered":"<p>Nightingale (Sayonakidori, \u30b5\u30e8\u30ca\u30ad\u30c9\u30ea) [Chorus]\u4eca\u3000\u9022\u3048\u306a\u3044\u591c\u3092\u8d8a\u3048\u3066\u80f8\u306b\u6f5c\u3081\u305f\u601d\u3044\u51fa\u304c\u7a81\u7136\u3075\u3063\u3068\u7526\u3048\u308b\u306e\u5fc3\u306f\u596a\u308f\u308c\u3066\u5fc3\u306f\u596a\u308f\u308c\u305f\u307e\u307e [Verse 1]Translucent\u307b\u3093\u306e\u5c11\u3057\u9858\u3063\u3066\u307f\u305f\u306e\u3067\u3082\u306d Translucent\u3042\u306e\u65e5\u306e\u8a00\u8449\u3000\u5fd8\u308c\u306a\u3044\u3067\u3057\u3087\u3046 [Pre-Chorus]\u6bce\u65e5\u3092\u6372\u308b\u5ea6\u3000\u5fc3\u306f\u4f55\u3082\u304b\u3082\u8ffd\u3044\u8d8a\u3057\u3066\u3057\u307e\u3046\u306e\u9192\u3081\u306a\u3044\u3067\u3053\u306e\u307e\u307e\u306e\u771f\u591c\u4e2d\u3067\u305a\u3063\u3068\u3001\u305a\u3063\u3068\u3001\u305a\u3063\u3068\u60b2\u3057\u3044\u6c17\u6301\u3061\u3082\u63fa\u308c\u308b\u77b3\u3082\u9023\u308c\u3066\u3086\u304f\u304b\u3089 [Chorus]\u4eca\u3000\u30a2\u30a4\u3092\u898b\u3064\u3051\u305f\u3000\u30a2\u30a4\u3092\u7f6e\u3044\u3066\u304b\u306a\u3044\u3067\u3000\u5922\u306e\u4e2d\u9022\u3044\u305f\u304f\u3066\u3082\u9022\u3044\u306b\u884c\u3051\u306a\u3044\u6642\u306f\u305f\u3060\u904e\u304e\u3066\u3044\u304f\u9022\u3048\u306a\u3044\u591c\u3092\u8d8a\u3048\u3066\u80f8\u306b\u6f5c\u3081\u305f\u601d\u3044\u51fa\u304c\u7a81\u7136\u3075\u3063\u3068\u7526\u3048\u308b\u306e\u5fc3\u306f\u596a\u308f\u308c\u3066\u5fc3\u306f\u596a\u308f\u308c\u305f\u307e\u307e [Verse 2]\u6b62\u307e\u3089\u306a\u3044 Circulation\u8a70\u307e\u308b\u547c\u5438\u3000\u4e0d\u7532\u6590\u7121\u3044\u3093\u3060\u3088\u305d\u308c\u3067\u3082\u307e\u3060 Circulation\u30d0\u30ec\u305f\u304f\u306a\u3044\u3000\u7b11\u3063\u3066\u307f\u305f\u306e [Pre-Chorus]\u3069\u3053\u307e\u3067\u3082\u3000\u5883\u754c\u7dda\u5f62\u306e\u306a\u3044\u6e07\u671b\u6c42\u3081\u3066\u3082\u3044\u3044\u5b50\u306a\u3093\u304b\u306a\u308c\u306a\u3044\u7269\u8a9e\u3000\u62b1\u304d\u3057\u3081\u3066\u7720\u308b\u307e\u3067\u3082\u3063\u3068\u3001\u3082\u3063\u3068\u3001\u3082\u3063\u3068\u3001\u3082\u3063\u3068 \u5f37\u304f\u4ed6\u3058\u3083\u9055\u3046\u306e\uff1f\u4eca\u3058\u3083\u3060\u3081\u306a\u306e\uff1f\u98f2\u307f\u8fbc\u307e\u308c\u3066\u304f [Chorus]\u3082\u3046\u3000\u30a2\u30a4\u306b\u51fa\u4f1a\u3048\u305f\u3000\u30a2\u30a4\u306b\u6d88\u3048\u3066\u3057\u307e\u3046\u3093\u3060\u3000\u80f8\u306e\u4e2d\u9022\u3044\u305f\u304f\u3066\u3082\u9022\u3044\u306b\u306f\u6765\u306a\u3044\u60f3\u3044\u3042\u306e\u65e5\u306e\u307e\u307e\u9022\u3048\u306a\u3044\u591c\u3092\u8d8a\u3048\u3066\u80f8\u306b\u6f5c\u3081\u305f\u601d\u3044\u51fa\u304c\u7a81\u7136\u3075\u3063\u3068\u7526\u3048\u308b\u306e\u5fc3\u306f\u596a\u308f\u308c\u3066\u5fc3\u306f\u596a\u308f\u308c\u3066\u3044\u304f [Spoken]My bounty is as boundless as the seaMy love as deep, the more I give to theeThe more I have, for both are infinite [Chorus]\u305f\u3060\u3000\u30a2\u30a4\u306b\u6eba\u308c\u305f\u3000\u30a2\u30a4\u3092\u601d\u3044\u51fa\u3059\u3093\u3060\u3000\u5922\u306e\u5f8c\u3055\u3088\u306a\u3089\u3055\u3048\u3000\u611b\u3057\u3066\u305f\u3088\u3072\u3068\u308a\u3000\u76ee\u3092\u9589\u3058\u305f\u306e\u9022\u3048\u306a\u3044\u591c\u3092\u8d8a\u3048\u3066\u96f6\u308c\u843d\u3061\u3066\u3063\u305f\u601d\u3044\u51fa\u306f\u5927\u4eba\u306b\u306a\u3093\u3066\u306a\u308c\u306a\u304f\u3066\u3044\u3044\u5fc3\u306f\u596a\u308f\u308c\u3066\u5fc3\u306f\u596a\u308f\u308c\u305f\u307e\u307e [Post-Chorus]\u91cd\u306d\u305f\u8a00\u8449\u3000\u7e4b\u3044\u3060\u624b\u3068\u624b\u3082\u3046\u5c11\u3057\u3060\u3051\u3068\u585e\u3044\u3060\u6ce1\u306b\u304d\u3048\u3066\u3082\u30a8\u30b4\u3067\u3082\u3044\u3044\u5fc3\u3000\u58ca\u305b\u306a\u3044\u306e\u8d64\u304f\u67d3\u3081\u3066\u304f\u51f8\u51f9\u306e\u307e\u307e\u3069\u3046\u304b\u9858\u3044\u53f6\u3046\u306a\u3089\u5fc3\u306f\u596a\u308f\u308c\u305f\u307e\u307e Nightingale (Sayonakidori, \u30b5\u30e8\u30ca\u30ad\u30c9\u30ea) (Paroles romanis\u00e9es) [Chorus]Ima aenai yoru o koeteMune ni hisometa omoide &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.band-maid.fr\/index.php\/nightingale\/\" class=\"more-link\">Lire la suite de<span class=\"screen-reader-text\">\u00ab\u00a0Nightingale (Sayonakidori, \u30b5\u30e8\u30ca\u30ad\u30c9\u30ea)\u00a0\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":9170,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"class_list":["post-9187","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nightingale (Sayonakidori, \u30b5\u30e8\u30ca\u30ad\u30c9\u30ea) - BAND-MAID<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.band-maid.fr\/index.php\/nightingale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nightingale (Sayonakidori, \u30b5\u30e8\u30ca\u30ad\u30c9\u30ea) - BAND-MAID\" \/>\n<meta property=\"og:description\" content=\"Nightingale (Sayonakidori, \u30b5\u30e8\u30ca\u30ad\u30c9\u30ea) [Chorus]\u4eca\u3000\u9022\u3048\u306a\u3044\u591c\u3092\u8d8a\u3048\u3066\u80f8\u306b\u6f5c\u3081\u305f\u601d\u3044\u51fa\u304c\u7a81\u7136\u3075\u3063\u3068\u7526\u3048\u308b\u306e\u5fc3\u306f\u596a\u308f\u308c\u3066\u5fc3\u306f\u596a\u308f\u308c\u305f\u307e\u307e [Verse 1]Translucent\u307b\u3093\u306e\u5c11\u3057\u9858\u3063\u3066\u307f\u305f\u306e\u3067\u3082\u306d Translucent\u3042\u306e\u65e5\u306e\u8a00\u8449\u3000\u5fd8\u308c\u306a\u3044\u3067\u3057\u3087\u3046 [Pre-Chorus]\u6bce\u65e5\u3092\u6372\u308b\u5ea6\u3000\u5fc3\u306f\u4f55\u3082\u304b\u3082\u8ffd\u3044\u8d8a\u3057\u3066\u3057\u307e\u3046\u306e\u9192\u3081\u306a\u3044\u3067\u3053\u306e\u307e\u307e\u306e\u771f\u591c\u4e2d\u3067\u305a\u3063\u3068\u3001\u305a\u3063\u3068\u3001\u305a\u3063\u3068\u60b2\u3057\u3044\u6c17\u6301\u3061\u3082\u63fa\u308c\u308b\u77b3\u3082\u9023\u308c\u3066\u3086\u304f\u304b\u3089 [Chorus]\u4eca\u3000\u30a2\u30a4\u3092\u898b\u3064\u3051\u305f\u3000\u30a2\u30a4\u3092\u7f6e\u3044\u3066\u304b\u306a\u3044\u3067\u3000\u5922\u306e\u4e2d\u9022\u3044\u305f\u304f\u3066\u3082\u9022\u3044\u306b\u884c\u3051\u306a\u3044\u6642\u306f\u305f\u3060\u904e\u304e\u3066\u3044\u304f\u9022\u3048\u306a\u3044\u591c\u3092\u8d8a\u3048\u3066\u80f8\u306b\u6f5c\u3081\u305f\u601d\u3044\u51fa\u304c\u7a81\u7136\u3075\u3063\u3068\u7526\u3048\u308b\u306e\u5fc3\u306f\u596a\u308f\u308c\u3066\u5fc3\u306f\u596a\u308f\u308c\u305f\u307e\u307e [Verse 2]\u6b62\u307e\u3089\u306a\u3044 Circulation\u8a70\u307e\u308b\u547c\u5438\u3000\u4e0d\u7532\u6590\u7121\u3044\u3093\u3060\u3088\u305d\u308c\u3067\u3082\u307e\u3060 Circulation\u30d0\u30ec\u305f\u304f\u306a\u3044\u3000\u7b11\u3063\u3066\u307f\u305f\u306e [Pre-Chorus]\u3069\u3053\u307e\u3067\u3082\u3000\u5883\u754c\u7dda\u5f62\u306e\u306a\u3044\u6e07\u671b\u6c42\u3081\u3066\u3082\u3044\u3044\u5b50\u306a\u3093\u304b\u306a\u308c\u306a\u3044\u7269\u8a9e\u3000\u62b1\u304d\u3057\u3081\u3066\u7720\u308b\u307e\u3067\u3082\u3063\u3068\u3001\u3082\u3063\u3068\u3001\u3082\u3063\u3068\u3001\u3082\u3063\u3068 \u5f37\u304f\u4ed6\u3058\u3083\u9055\u3046\u306e\uff1f\u4eca\u3058\u3083\u3060\u3081\u306a\u306e\uff1f\u98f2\u307f\u8fbc\u307e\u308c\u3066\u304f [Chorus]\u3082\u3046\u3000\u30a2\u30a4\u306b\u51fa\u4f1a\u3048\u305f\u3000\u30a2\u30a4\u306b\u6d88\u3048\u3066\u3057\u307e\u3046\u3093\u3060\u3000\u80f8\u306e\u4e2d\u9022\u3044\u305f\u304f\u3066\u3082\u9022\u3044\u306b\u306f\u6765\u306a\u3044\u60f3\u3044\u3042\u306e\u65e5\u306e\u307e\u307e\u9022\u3048\u306a\u3044\u591c\u3092\u8d8a\u3048\u3066\u80f8\u306b\u6f5c\u3081\u305f\u601d\u3044\u51fa\u304c\u7a81\u7136\u3075\u3063\u3068\u7526\u3048\u308b\u306e\u5fc3\u306f\u596a\u308f\u308c\u3066\u5fc3\u306f\u596a\u308f\u308c\u3066\u3044\u304f [Spoken]My bounty is as boundless as the seaMy love as deep, the more I give to theeThe more I have, for both are infinite [Chorus]\u305f\u3060\u3000\u30a2\u30a4\u306b\u6eba\u308c\u305f\u3000\u30a2\u30a4\u3092\u601d\u3044\u51fa\u3059\u3093\u3060\u3000\u5922\u306e\u5f8c\u3055\u3088\u306a\u3089\u3055\u3048\u3000\u611b\u3057\u3066\u305f\u3088\u3072\u3068\u308a\u3000\u76ee\u3092\u9589\u3058\u305f\u306e\u9022\u3048\u306a\u3044\u591c\u3092\u8d8a\u3048\u3066\u96f6\u308c\u843d\u3061\u3066\u3063\u305f\u601d\u3044\u51fa\u306f\u5927\u4eba\u306b\u306a\u3093\u3066\u306a\u308c\u306a\u304f\u3066\u3044\u3044\u5fc3\u306f\u596a\u308f\u308c\u3066\u5fc3\u306f\u596a\u308f\u308c\u305f\u307e\u307e [Post-Chorus]\u91cd\u306d\u305f\u8a00\u8449\u3000\u7e4b\u3044\u3060\u624b\u3068\u624b\u3082\u3046\u5c11\u3057\u3060\u3051\u3068\u585e\u3044\u3060\u6ce1\u306b\u304d\u3048\u3066\u3082\u30a8\u30b4\u3067\u3082\u3044\u3044\u5fc3\u3000\u58ca\u305b\u306a\u3044\u306e\u8d64\u304f\u67d3\u3081\u3066\u304f\u51f8\u51f9\u306e\u307e\u307e\u3069\u3046\u304b\u9858\u3044\u53f6\u3046\u306a\u3089\u5fc3\u306f\u596a\u308f\u308c\u305f\u307e\u307e Nightingale (Sayonakidori, \u30b5\u30e8\u30ca\u30ad\u30c9\u30ea) (Paroles romanis\u00e9es) [Chorus]Ima aenai yoru o koeteMune ni hisometa omoide &hellip; Lire la suite de\u00ab\u00a0Nightingale (Sayonakidori, \u30b5\u30e8\u30ca\u30ad\u30c9\u30ea)\u00a0\u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.band-maid.fr\/index.php\/nightingale\/\" \/>\n<meta property=\"og:site_name\" content=\"BAND-MAID\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bandmaid\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-30T20:50:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/bandeau-Unseen-World2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@bandmaid\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/index.php\\\/nightingale\\\/\",\"url\":\"https:\\\/\\\/www.band-maid.fr\\\/index.php\\\/nightingale\\\/\",\"name\":\"Nightingale (Sayonakidori, \u30b5\u30e8\u30ca\u30ad\u30c9\u30ea) - BAND-MAID\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/index.php\\\/nightingale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/index.php\\\/nightingale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.band-maid.fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/bandeau-Unseen-World2.jpg\",\"datePublished\":\"2026-04-02T16:26:29+00:00\",\"dateModified\":\"2026-04-30T20:50:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/index.php\\\/nightingale\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.band-maid.fr\\\/index.php\\\/nightingale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/index.php\\\/nightingale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.band-maid.fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/bandeau-Unseen-World2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.band-maid.fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/bandeau-Unseen-World2.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/index.php\\\/nightingale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.band-maid.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nightingale (Sayonakidori, \u30b5\u30e8\u30ca\u30ad\u30c9\u30ea)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.band-maid.fr\\\/\",\"name\":\"BAND-MAID\",\"description\":\"WORLD DOMINATION\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.band-maid.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/#organization\",\"name\":\"BAND-MAID\",\"url\":\"https:\\\/\\\/www.band-maid.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/wglgkdc.cluster121.hosting.ovh.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logo_band-maid_b.png\",\"contentUrl\":\"http:\\\/\\\/wglgkdc.cluster121.hosting.ovh.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logo_band-maid_b.png\",\"width\":540,\"height\":93,\"caption\":\"BAND-MAID\"},\"image\":{\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/bandmaid\",\"https:\\\/\\\/x.com\\\/bandmaid\",\"https:\\\/\\\/www.instagram.com\\\/bandmaid.jp\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCJToUvYrmkmTCR-bluEaQfA\",\"https:\\\/\\\/www.tiktok.com\\\/@bandmaid_int\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nightingale (Sayonakidori, \u30b5\u30e8\u30ca\u30ad\u30c9\u30ea) - BAND-MAID","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.band-maid.fr\/index.php\/nightingale\/","og_locale":"fr_FR","og_type":"article","og_title":"Nightingale (Sayonakidori, \u30b5\u30e8\u30ca\u30ad\u30c9\u30ea) - BAND-MAID","og_description":"Nightingale (Sayonakidori, \u30b5\u30e8\u30ca\u30ad\u30c9\u30ea) [Chorus]\u4eca\u3000\u9022\u3048\u306a\u3044\u591c\u3092\u8d8a\u3048\u3066\u80f8\u306b\u6f5c\u3081\u305f\u601d\u3044\u51fa\u304c\u7a81\u7136\u3075\u3063\u3068\u7526\u3048\u308b\u306e\u5fc3\u306f\u596a\u308f\u308c\u3066\u5fc3\u306f\u596a\u308f\u308c\u305f\u307e\u307e [Verse 1]Translucent\u307b\u3093\u306e\u5c11\u3057\u9858\u3063\u3066\u307f\u305f\u306e\u3067\u3082\u306d Translucent\u3042\u306e\u65e5\u306e\u8a00\u8449\u3000\u5fd8\u308c\u306a\u3044\u3067\u3057\u3087\u3046 [Pre-Chorus]\u6bce\u65e5\u3092\u6372\u308b\u5ea6\u3000\u5fc3\u306f\u4f55\u3082\u304b\u3082\u8ffd\u3044\u8d8a\u3057\u3066\u3057\u307e\u3046\u306e\u9192\u3081\u306a\u3044\u3067\u3053\u306e\u307e\u307e\u306e\u771f\u591c\u4e2d\u3067\u305a\u3063\u3068\u3001\u305a\u3063\u3068\u3001\u305a\u3063\u3068\u60b2\u3057\u3044\u6c17\u6301\u3061\u3082\u63fa\u308c\u308b\u77b3\u3082\u9023\u308c\u3066\u3086\u304f\u304b\u3089 [Chorus]\u4eca\u3000\u30a2\u30a4\u3092\u898b\u3064\u3051\u305f\u3000\u30a2\u30a4\u3092\u7f6e\u3044\u3066\u304b\u306a\u3044\u3067\u3000\u5922\u306e\u4e2d\u9022\u3044\u305f\u304f\u3066\u3082\u9022\u3044\u306b\u884c\u3051\u306a\u3044\u6642\u306f\u305f\u3060\u904e\u304e\u3066\u3044\u304f\u9022\u3048\u306a\u3044\u591c\u3092\u8d8a\u3048\u3066\u80f8\u306b\u6f5c\u3081\u305f\u601d\u3044\u51fa\u304c\u7a81\u7136\u3075\u3063\u3068\u7526\u3048\u308b\u306e\u5fc3\u306f\u596a\u308f\u308c\u3066\u5fc3\u306f\u596a\u308f\u308c\u305f\u307e\u307e [Verse 2]\u6b62\u307e\u3089\u306a\u3044 Circulation\u8a70\u307e\u308b\u547c\u5438\u3000\u4e0d\u7532\u6590\u7121\u3044\u3093\u3060\u3088\u305d\u308c\u3067\u3082\u307e\u3060 Circulation\u30d0\u30ec\u305f\u304f\u306a\u3044\u3000\u7b11\u3063\u3066\u307f\u305f\u306e [Pre-Chorus]\u3069\u3053\u307e\u3067\u3082\u3000\u5883\u754c\u7dda\u5f62\u306e\u306a\u3044\u6e07\u671b\u6c42\u3081\u3066\u3082\u3044\u3044\u5b50\u306a\u3093\u304b\u306a\u308c\u306a\u3044\u7269\u8a9e\u3000\u62b1\u304d\u3057\u3081\u3066\u7720\u308b\u307e\u3067\u3082\u3063\u3068\u3001\u3082\u3063\u3068\u3001\u3082\u3063\u3068\u3001\u3082\u3063\u3068 \u5f37\u304f\u4ed6\u3058\u3083\u9055\u3046\u306e\uff1f\u4eca\u3058\u3083\u3060\u3081\u306a\u306e\uff1f\u98f2\u307f\u8fbc\u307e\u308c\u3066\u304f [Chorus]\u3082\u3046\u3000\u30a2\u30a4\u306b\u51fa\u4f1a\u3048\u305f\u3000\u30a2\u30a4\u306b\u6d88\u3048\u3066\u3057\u307e\u3046\u3093\u3060\u3000\u80f8\u306e\u4e2d\u9022\u3044\u305f\u304f\u3066\u3082\u9022\u3044\u306b\u306f\u6765\u306a\u3044\u60f3\u3044\u3042\u306e\u65e5\u306e\u307e\u307e\u9022\u3048\u306a\u3044\u591c\u3092\u8d8a\u3048\u3066\u80f8\u306b\u6f5c\u3081\u305f\u601d\u3044\u51fa\u304c\u7a81\u7136\u3075\u3063\u3068\u7526\u3048\u308b\u306e\u5fc3\u306f\u596a\u308f\u308c\u3066\u5fc3\u306f\u596a\u308f\u308c\u3066\u3044\u304f [Spoken]My bounty is as boundless as the seaMy love as deep, the more I give to theeThe more I have, for both are infinite [Chorus]\u305f\u3060\u3000\u30a2\u30a4\u306b\u6eba\u308c\u305f\u3000\u30a2\u30a4\u3092\u601d\u3044\u51fa\u3059\u3093\u3060\u3000\u5922\u306e\u5f8c\u3055\u3088\u306a\u3089\u3055\u3048\u3000\u611b\u3057\u3066\u305f\u3088\u3072\u3068\u308a\u3000\u76ee\u3092\u9589\u3058\u305f\u306e\u9022\u3048\u306a\u3044\u591c\u3092\u8d8a\u3048\u3066\u96f6\u308c\u843d\u3061\u3066\u3063\u305f\u601d\u3044\u51fa\u306f\u5927\u4eba\u306b\u306a\u3093\u3066\u306a\u308c\u306a\u304f\u3066\u3044\u3044\u5fc3\u306f\u596a\u308f\u308c\u3066\u5fc3\u306f\u596a\u308f\u308c\u305f\u307e\u307e [Post-Chorus]\u91cd\u306d\u305f\u8a00\u8449\u3000\u7e4b\u3044\u3060\u624b\u3068\u624b\u3082\u3046\u5c11\u3057\u3060\u3051\u3068\u585e\u3044\u3060\u6ce1\u306b\u304d\u3048\u3066\u3082\u30a8\u30b4\u3067\u3082\u3044\u3044\u5fc3\u3000\u58ca\u305b\u306a\u3044\u306e\u8d64\u304f\u67d3\u3081\u3066\u304f\u51f8\u51f9\u306e\u307e\u307e\u3069\u3046\u304b\u9858\u3044\u53f6\u3046\u306a\u3089\u5fc3\u306f\u596a\u308f\u308c\u305f\u307e\u307e Nightingale (Sayonakidori, \u30b5\u30e8\u30ca\u30ad\u30c9\u30ea) (Paroles romanis\u00e9es) [Chorus]Ima aenai yoru o koeteMune ni hisometa omoide &hellip; Lire la suite de\u00ab\u00a0Nightingale (Sayonakidori, \u30b5\u30e8\u30ca\u30ad\u30c9\u30ea)\u00a0\u00bb","og_url":"https:\/\/www.band-maid.fr\/index.php\/nightingale\/","og_site_name":"BAND-MAID","article_publisher":"https:\/\/www.facebook.com\/bandmaid","article_modified_time":"2026-04-30T20:50:47+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/bandeau-Unseen-World2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@bandmaid","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.band-maid.fr\/index.php\/nightingale\/","url":"https:\/\/www.band-maid.fr\/index.php\/nightingale\/","name":"Nightingale (Sayonakidori, \u30b5\u30e8\u30ca\u30ad\u30c9\u30ea) - BAND-MAID","isPartOf":{"@id":"https:\/\/www.band-maid.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.band-maid.fr\/index.php\/nightingale\/#primaryimage"},"image":{"@id":"https:\/\/www.band-maid.fr\/index.php\/nightingale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/bandeau-Unseen-World2.jpg","datePublished":"2026-04-02T16:26:29+00:00","dateModified":"2026-04-30T20:50:47+00:00","breadcrumb":{"@id":"https:\/\/www.band-maid.fr\/index.php\/nightingale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.band-maid.fr\/index.php\/nightingale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.band-maid.fr\/index.php\/nightingale\/#primaryimage","url":"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/bandeau-Unseen-World2.jpg","contentUrl":"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/bandeau-Unseen-World2.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.band-maid.fr\/index.php\/nightingale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.band-maid.fr\/"},{"@type":"ListItem","position":2,"name":"Nightingale (Sayonakidori, \u30b5\u30e8\u30ca\u30ad\u30c9\u30ea)"}]},{"@type":"WebSite","@id":"https:\/\/www.band-maid.fr\/#website","url":"https:\/\/www.band-maid.fr\/","name":"BAND-MAID","description":"WORLD DOMINATION","publisher":{"@id":"https:\/\/www.band-maid.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.band-maid.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.band-maid.fr\/#organization","name":"BAND-MAID","url":"https:\/\/www.band-maid.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.band-maid.fr\/#\/schema\/logo\/image\/","url":"http:\/\/wglgkdc.cluster121.hosting.ovh.net\/wp-content\/uploads\/2026\/01\/logo_band-maid_b.png","contentUrl":"http:\/\/wglgkdc.cluster121.hosting.ovh.net\/wp-content\/uploads\/2026\/01\/logo_band-maid_b.png","width":540,"height":93,"caption":"BAND-MAID"},"image":{"@id":"https:\/\/www.band-maid.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bandmaid","https:\/\/x.com\/bandmaid","https:\/\/www.instagram.com\/bandmaid.jp\/","https:\/\/www.youtube.com\/channel\/UCJToUvYrmkmTCR-bluEaQfA","https:\/\/www.tiktok.com\/@bandmaid_int"]}]}},"coauthors":[],"author_meta":{"author_link":"https:\/\/www.band-maid.fr\/index.php\/author\/admin8693\/","display_name":"LJB"},"relative_dates":{"created":"Publi\u00e9 1 mois il y a","modified":"Mis \u00e0 jour 2 semaines il y a"},"absolute_dates":{"created":"Publi\u00e9 le 02\/04\/2026","modified":"Mise \u00e0 jour le 30\/04\/2026"},"absolute_dates_time":{"created":"Publi\u00e9 le 02\/04\/2026 16h26","modified":"Mise \u00e0 jour le 30\/04\/2026 20h50"},"featured_img_caption":"","featured_img":"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/bandeau-Unseen-World2.jpg","series_order":"","featured_media_urls":{"thumbnail":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/bandeau-Unseen-World2-150x150.jpg",150,150,true],"medium":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/bandeau-Unseen-World2-300x300.jpg",300,300,true],"medium_large":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/bandeau-Unseen-World2.jpg",768,768,false],"large":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/bandeau-Unseen-World2-1024x1024.jpg",950,950,true],"1536x1536":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/bandeau-Unseen-World2.jpg",1200,1200,false],"2048x2048":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/bandeau-Unseen-World2.jpg",1200,1200,false],"inspiro-featured-image":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/bandeau-Unseen-World2.jpg",1200,1200,false],"inspiro-loop":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/bandeau-Unseen-World2-950x320.jpg",950,320,true],"inspiro-loop@2x":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/bandeau-Unseen-World2-1200x640.jpg",1200,640,true],"portfolio_item-thumbnail":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/bandeau-Unseen-World2-600x400.jpg",600,400,true],"portfolio_item-thumbnail@2x":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/bandeau-Unseen-World2-1200x800.jpg",1200,800,true],"portfolio_item-masonry":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/bandeau-Unseen-World2-600x600.jpg",600,600,true],"portfolio_item-masonry@2x":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/bandeau-Unseen-World2.jpg",1200,1200,false],"portfolio_item-thumbnail_cinema":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/bandeau-Unseen-World2-800x335.jpg",800,335,true],"portfolio_item-thumbnail_portrait":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/bandeau-Unseen-World2-600x900.jpg",600,900,true],"portfolio_item-thumbnail_portrait@2x":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/bandeau-Unseen-World2.jpg",1200,1200,false],"portfolio_item-thumbnail_square":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/04\/bandeau-Unseen-World2-800x800.jpg",800,800,true]},"_links":{"self":[{"href":"https:\/\/www.band-maid.fr\/index.php\/wp-json\/wp\/v2\/pages\/9187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.band-maid.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.band-maid.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.band-maid.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.band-maid.fr\/index.php\/wp-json\/wp\/v2\/comments?post=9187"}],"version-history":[{"count":2,"href":"https:\/\/www.band-maid.fr\/index.php\/wp-json\/wp\/v2\/pages\/9187\/revisions"}],"predecessor-version":[{"id":10299,"href":"https:\/\/www.band-maid.fr\/index.php\/wp-json\/wp\/v2\/pages\/9187\/revisions\/10299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.band-maid.fr\/index.php\/wp-json\/wp\/v2\/media\/9170"}],"wp:attachment":[{"href":"https:\/\/www.band-maid.fr\/index.php\/wp-json\/wp\/v2\/media?parent=9187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}