{"id":8486,"date":"2026-02-05T21:54:53","date_gmt":"2026-02-05T21:54:53","guid":{"rendered":"https:\/\/www.band-maid.fr\/?page_id=8486"},"modified":"2026-05-03T11:09:32","modified_gmt":"2026-05-03T11:09:32","slug":"super-sunshine-super-soleil","status":"publish","type":"page","link":"https:\/\/www.band-maid.fr\/index.php\/super-sunshine-super-soleil\/","title":{"rendered":"SUPER SUNSHINE"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"78\" src=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg\" alt=\"\" class=\"wp-image-8482\" srcset=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg 1024w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-300x23.jpg 300w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"SUPER SUNSHINE\" width=\"950\" height=\"713\" src=\"https:\/\/www.youtube.com\/embed\/J_dd47xa31E?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"78\" src=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg\" alt=\"\" class=\"wp-image-8482\" srcset=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg 1024w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-300x23.jpg 300w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-advgb-columns advgb-columns-wrapper\" id=\"advgb-cols-1a8e2492-aab6-4967-9513-e620fee8f661\"><div class=\"advgb-columns-container\"><div class=\"advgb-columns advgb-columns-row advgb-is-mobile advgb-columns-3 layout-13-13-13 mbl-layout-stacked vgutter-10\">\n<div class=\"wp-block-advgb-column advgb-column\" id=\"advgb-col-32f567f2-7baa-4d81-a6db-f2c96cb0bbfc\"><div class=\"advgb-column-inner\" style=\"border-style:none;border-width:1px\">\n<p class=\"has-text-align-center\"><strong><a href=\"#SUPER-SUNSHINE\">Paroles officielles<\/a><\/strong><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-advgb-column advgb-column\" id=\"advgb-col-7badd8ee-f522-410c-b200-a6d87093428e\"><div class=\"advgb-column-inner\" style=\"border-style:none;border-width:1px\">\n<p class=\"has-text-align-center\"><strong><a href=\"#romanis\u00e9es\">Paroles romanis\u00e9es<\/a><\/strong><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-advgb-column advgb-column\" id=\"advgb-col-d335750b-ba7d-4700-b605-fae16f5032b1\"><div class=\"advgb-column-inner\" style=\"border-style:none;border-width:1px\">\n<p><strong><a href=\"#fran\u00e7ais\">Paroles en fran\u00e7ais<\/a><\/strong><\/p>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"SUPER-SUNSHINE\">SUPER SUNSHINE <\/h2>\n\n\n\n<p>[Verse 1]<br>I wanna dive<br>\u66d6\u6627\u306a\u672a\u6765\u3000\u585e\u3050\u4e16\u754c\u3000\u8ced\u3051\u308b\u52c7\u6c17\u3092\u304f\u308c<br>\u7b54\u3048\u306a\u3093\u3066\u3000\u306f\u3058\u3081\u304b\u3089\u8981\u3089\u306a\u3044<br>I wanna change your mind<br>\u60a9\u3093\u3060\u65e5\u3005\u3060\u3063\u3066\u3000\u304d\u3063\u3068\u7ce7\u306b\u306a\u308b\u304b\u3089<br>\u8e0f\u307f\u51fa\u3059\u3093\u3060 the time has come<\/p>\n\n\n\n<p>[Pre-Chorus]<br>Give it a try try\u3000\u3053\u306e\u307e\u307e\u3058\u3083\u307e\u3060<br>Fight for your pride pride<br>\u7d42\u308f\u308c\u306a\u3044\u3088<br>\u971e\u3080\u660e\u65e5\u306b\u602f\u3048\u306a\u3044<br>\u4eca\u3092\u751f\u304d\u3066\u307f\u305b\u308b<br>(Run into the light)<\/p>\n\n\n\n<p>[Chorus]<br>I will get to it<br>\u8ff7\u3063\u3066\u3082\u69cb\u308f\u306a\u3044<br>Don&rsquo;t miss it\u3000\u9032\u3081<br>\u3053\u306e\u624b\u306b\u63b4\u307f\u53d6\u308b\u3088<br>\u4e16\u754c\u3092\u5909\u3048\u308b<br>SUPER SUNSHINE<\/p>\n\n\n\n<p>[Verse 2]<br>No looking back<br>\u99c6\u3051\u629c\u3051\u3066\u3044\u304f<br>\u4e0d\u5b89\u3060\u3063\u3066\u80cc\u8ca0\u3063\u3066\u751f\u304d\u308b\u3060\u3051\u3055<br>\u4fe1\u3058\u305f\u9053<br>Let&rsquo;s roll it<\/p>\n\n\n\n<p>[Pre-Chorus]<br>Rat-a-tat-tat-tat<br>\u97f3\u306b\u5408\u308f\u305b\u3066<br>Rat-a-tat-tat-tat-tat<br>\u523b\u3081<br>\u53eb\u3076\u3053\u306e\u58f0\u306f\u6d88\u3048\u306a\u3044<br>\u4e8c\u5ea6\u3068\u632f\u308a\u5411\u304b\u306a\u3044\u3088<br>(Through the night, I&rsquo;ll follow my own way)<\/p>\n\n\n\n<p>[Chorus]<br>I will never die<br>\u8fbf\u308a\u7740\u304f\u65e5\u307e\u3067<br>Don&rsquo;t let go\u3000\u9032\u3081<br>\u6d41\u3057\u305f\u6d99\u3055\u3048\u3082<br>\u7121\u99c4\u306b\u3057\u306a\u3044<br>SUPER SUNSHINE<\/p>\n\n\n\n<p>[Bass solo]<\/p>\n\n\n\n<p>[Bridge]<br>Don&rsquo;t waste your life<br>\u3044\u3064\u304b\u5fc5\u305a<br>\u63b4\u307f\u53d6\u308b\u305f\u3081\u3000\u305f\u3060\u7a81\u304d\u9032\u3081<br>Follow me<br>\u4f55\u5ea6\u3060\u3063\u3066 Try out<br>\u4f55\u3082\u304b\u3082\u3092\u8ae6\u3081\u306a\u3044<\/p>\n\n\n\n<p>[Guitar solo]<\/p>\n\n\n\n<p>[Pre-Chorus]<br>Give it a try try\u3000\u3053\u306e\u307e\u307e\u3058\u3083\u307e\u3060<br>Fight for your pride pride<br>\u7d42\u308f\u308c\u306a\u3044\u3088<br>\u971e\u3080\u660e\u65e5\u306b\u602f\u3048\u306a\u3044<br>\u4eca\u3092\u751f\u304d\u3066\u307f\u305b\u308b<\/p>\n\n\n\n<p>[Breakdown]<br>Even if you fall into darkness<br>\u5fc3\u306b\u706f\u308b\u708e\u306f\u307e\u3060<br>\u71c3\u3048\u7d9a\u3051\u308b\u3088<br>\u511a\u3044\u5922\u3058\u3083<br>\u7d42\u308f\u3089\u305b\u306a\u3044\u304b\u3089<br>(Through the dark, I&rsquo;ll follow my own way)<\/p>\n\n\n\n<p>[Chorus]<br>I will get to it<br>\u8ff7\u3063\u3066\u3082\u69cb\u308f\u306a\u3044<br>Don&rsquo;t miss it\u3000\u9032\u3081<br>\u3053\u306e\u624b\u306b\u63b4\u307f\u53d6\u308b\u3088<br>\u4e16\u754c\u3092\u5909\u3048\u308b<br>(Super Sunshine)<\/p>\n\n\n\n<p>Never die<br>\u8fbf\u308a\u7740\u304f\u65e5\u307e\u3067<br>Don&rsquo;t let go\u3000\u9032\u3081<br>\u60b2\u3057\u307f\u3055\u3048\u3082<br>\u7121\u99c4\u306b\u3057\u306a\u3044<br>SUPER SUNSHINE<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"78\" src=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg\" alt=\"\" class=\"wp-image-8482\" srcset=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg 1024w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-300x23.jpg 300w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-6c531013 wp-block-group-is-layout-flex\">\n<h2 class=\"wp-block-heading\" id=\"romanis\u00e9es\">SUPER SUNSHINE (Paroles romanis\u00e9es)<\/h2>\n\n\n\n<p><\/p>\n<\/div>\n\n\n\n<p>[Verse 1]<br>I wanna dive<br>Aimai na mirai fusagu sekai kakeru yuuki wo kure<br>Kotae nante hajimekara iranai<br>I wanna change your mind<br>Nayanda hibi datte kitto kate ni naru kara<br>Fumidasu nda, the time has come<\/p>\n\n\n\n<p>[Pre-Chorus]<br>Give it a try try, Konomama ja mada<br>Fight for your pride pride<br>Owarenai yo<br>Kasumu ashita ni obienai<br>Ima wo ikite miseru<br>(Run into the light)<\/p>\n\n\n\n<p>[Chorus]<br>I will get to it<br>Mayotte mo kamawanai<br>Don&rsquo;t miss it, Susume<br>Kono te ni tsukami toru yo<br>Sekai wo kaeru<br>SUPER SUNSHINE<\/p>\n\n\n\n<p>[Verse 2]<br>No looking back<br>Kakenukete iku<br>Fuan datte seotte ikiru dake sa<br>Shinjita michi<br>Let&rsquo;s roll it<\/p>\n\n\n\n<p>[Pre-Chorus]<br>Rat-a-tat-tat-tat<br>Oto ni awasete<br>Rat-a-tat-tat-tat-tat<br>Kizame<br>Sakebu kono koe wa kienai<br>Nido to furimukanai yo<br>(Through the night, I&rsquo;ll follow my own way)<\/p>\n\n\n\n<p>[Chorus]<br>I will n\u0435ver die<br>Tadoritsuku hi made<br>Don&rsquo;t l\u0435t go, Susume<br>Nagashita namida sae mo<br>Muda ni shinai<br>SUPER SUNSHINE<\/p>\n\n\n\n<p>[Bass solo]<\/p>\n\n\n\n<p>[Bridge]<br>Don&rsquo;t waste your life<br>Itsuka kanarazu<br>Tsukamitoru tame tada tsukisusume<br>Follow me<br>Nando datte, Try out<br>Nanimo kamo wo akiramenai<\/p>\n\n\n\n<p>[Guitar solo]<\/p>\n\n\n\n<p>[Pre-Chorus]<br>Give it a try try, Konomama ja mada<br>Fight for your pride pride<br>Owarenai yo<br>Kasumu ashita ni obienai<br>Ima wo ikite miseru<\/p>\n\n\n\n<p>[Breakdown]<br>Even if you fall into darkness<br>Kokoro ni tomoru honoo wa mada<br>Moetsuzukeru yo<br>Hakanai yume ja<br>Owarasenai kara<br>(Through the dark, I&rsquo;ll follow my own way)<\/p>\n\n\n\n<p>[Chorus]<br>I will get to it<br>Mayotte mo kamawanai<br>Don&rsquo;t miss it, Susume<br>Kono te ni tsukamitoru yo<br>Sekai wo kaeru<br>(Super Sunshine)<\/p>\n\n\n\n<p>Never die<br>Tadoritsuku hi made<br>Don&rsquo;t let go, Susume<br>Kanashimi sae mo<br>Muda ni shinai<br>SUPER SUNSHINE<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"78\" src=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg\" alt=\"\" class=\"wp-image-8482\" srcset=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg 1024w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-300x23.jpg 300w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"fran\u00e7ais\">SUPER SUNSHINE (Paroles en fran\u00e7ais)<\/h2>\n\n\n\n<p>[Couplet 1]<br>Je veux me jeter \u00e0 l&rsquo;eau<br>Un avenir incertain, un monde \u00e9troit<br>Donne-moi le courage de parier contre toute attente<br>Je n&rsquo;ai plus besoin de r\u00e9ponses depuis que je me suis lanc\u00e9<br>Je veux te faire changer d&rsquo;avis<br>M\u00eame ces jours difficiles ne manqueront pas de me donner de la force<br>Avance, l&rsquo;heure est venue<\/p>\n\n\n\n<p>[Pr\u00e9-refrain]<br>Essaie, essaie, comme \u00e7a<br>Bats-toi pour ta fiert\u00e9<br>Je ne peux pas m&rsquo;arr\u00eater<br>Je n&rsquo;ai pas peur de ce lendemain incertain<br>Je vais te montrer comment je vis cet instant<br>(Cours vers la lumi\u00e8re)<\/p>\n\n\n\n<p>[Refrain]<br>J&rsquo;y arriverai<br>Peu m&rsquo;importe si je me perds<br>Ne rate pas \u00e7a, avance<br>Je vais le saisir de mes mains<br>Changer le monde<br>SUPER SUNSHINE<\/p>\n\n\n\n<p>[Couplet 2]<br>Pas de regard en arri\u00e8re<br>Je fonce \u00e0 travers<br>Je continue simplement \u00e0 vivre avec tous mes soucis sur le dos<br>Le chemin auquel j&rsquo;ai cru<br>C&rsquo;est parti<\/p>\n\n\n\n<p>[Pr\u00e9-refrain]<br>Rat-a-tat-tat-tat<br>\u00c9coute ce son<br>Rat-a-tat-tat-tat-tat<br>Grave-le en toi<br>Crie, ma voix ne s&rsquo;\u00e9teindra jamais<br>Je ne regarderai plus jamais en arri\u00e8re<br>(\u00c0 travers la nuit, je suivrai ma propre voie)<\/p>\n\n\n\n<p>[Refrain]<br>Je ne mourrai jamais<br>Jusqu&rsquo;au jour o\u00f9 j&rsquo;y arriverai<br>Ne l\u00e2che pas prise, avance<br>M\u00eame les larmes que je verse ne seront pas vaines<br>SUPER SUNSHINE<\/p>\n\n\n\n<p>[Solo de basse]<\/p>\n\n\n\n<p>[Pont]<br>Ne g\u00e2che pas ta vie<br>Un jour, sans aucun doute<br>Pour la saisir, continue d&rsquo;avancer<br>Suis-moi<br>Essaie autant de fois qu&rsquo;il le faut<br>Je n&rsquo;abandonnerai rien ni personne<\/p>\n\n\n\n<p>[Solo de guitare]<\/p>\n\n\n\n<p>[Pr\u00e9-refrain]<br>Essaie, essaie, comme \u00e7a<br>Bats-toi pour ta fiert\u00e9<br>Je ne peux pas m&rsquo;arr\u00eater<br>Je n&rsquo;ai pas peur d&rsquo;un avenir incertain<br>Je vais te montrer comment je vis cet instant<\/p>\n\n\n\n<p>[Breakdown]<br>M\u00eame si tu tombes dans les t\u00e9n\u00e8bres<br>La flamme allum\u00e9e dans mon c\u0153ur br\u00fble toujours<br>Je ne laisserai pas \u00e7a finir comme un r\u00eave \u00e9ph\u00e9m\u00e8re<br>(\u00c0 travers l&rsquo;obscurit\u00e9, je suivrai ma propre voie)<\/p>\n\n\n\n<p>[Refrain]<br>J&rsquo;y arriverai<br>Peu m&rsquo;importe si je me perds<br>Ne rate pas \u00e7a, avance<br>Je vais le saisir de mes mains<br>Changer le monde<br>(Super Sunshine)<\/p>\n\n\n\n<p>Ne meurs jamais<br>Jusqu&rsquo;au jour o\u00f9 j&rsquo;y arriverai<br>Ne l\u00e2che pas prise, avance<br>M\u00eame la tristesse ne sera pas vaine<br>SUPER SUNSHINE<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"78\" src=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg\" alt=\"\" class=\"wp-image-8482\" srcset=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg 1024w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-300x23.jpg 300w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Paroles: <strong>Saiki<\/strong><br>Musique: <strong>Band-Maid<\/strong><br>Album : <strong>SCOOOOOP<\/strong> (22 octobre 2025)<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"78\" src=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg\" alt=\"\" class=\"wp-image-8482\" srcset=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg 1024w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-300x23.jpg 300w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"notes-et-citations-bandmaid-songs-encyclopedia-7f479a8b-2b98-4693-b52f-9b98b8f26db3\">Notes et citations (Band-Maid Songs Encyclopedia)<\/h2>\n\n\n\n<p><strong>\u25a0<\/strong> <strong>Comment la chanson \u00ab SUPER SUNSHINE \u00bb a-t-elle vu le jour ?<br>Kanami<\/strong> : Tout a commenc\u00e9 par une d\u00e9mo il y a environ deux ans. Je crois que c&rsquo;\u00e9tait \u00e0 une \u00e9poque o\u00f9 nous jouions beaucoup dans des festivals et en concert. Je l&rsquo;ai \u00e9crite en pensant que ce serait sympa si m\u00eame ceux qui nous \u00e9coutaient pour la premi\u00e8re fois pouvaient<br>l&rsquo;appr\u00e9cier avec nous. La structure de la chanson est la m\u00eame qu&rsquo;il y a deux ans, mais j&rsquo;ai l&rsquo;impression que mon approche de l&rsquo;arrangement et de la composition a pas mal chang\u00e9 depuis. Il y avait tout de m\u00eame des aspects que j\u2019appr\u00e9ciais dans les id\u00e9es de mon<br>moi d\u2019autrefois, alors j\u2019ai conserv\u00e9 ces parties. Cependant, il y avait aussi des passages o\u00f9 je me disais : \u00ab \u00c7a ne correspond pas tout \u00e0 fait au BAND-MAID d\u2019aujourd\u2019hui \u00bb, alors je les ai r\u00e9actualis\u00e9s pour qu\u2019ils refl\u00e8tent qui nous sommes d\u00e9sormais. J\u2019esp\u00e8re que c\u2019est une chanson que m\u00eame les personnes qui nous d\u00e9couvrent pour la premi\u00e8re fois lors d\u2019un festival pourront appr\u00e9cier avec nous.<br><strong>Saiki <\/strong>: Depuis la cr\u00e9ation de la d\u00e9mo, nous l\u2019avons r\u00e9arrang\u00e9e \u00e0 de nombreuses reprises au cours de la derni\u00e8re ann\u00e9e et demie, tout en menant un calendrier charg\u00e9 de concerts. Depuis la sc\u00e8ne, je vois de nouveaux visages, mais il m\u2019arrive aussi parfois de remarquer : \u00ab Tiens, \u00e7a fait longtemps que je n\u2019ai pas vu cette personne. \u00bb Je ne suis pas du genre \u00e0 me laisser d\u00e9courager par \u00e7a, cependant. Je suis tr\u00e8s positive, alors je me dis : \u00ab Je veux faire de cet endroit un lieu o\u00f9 ils pourront revenir quand ils le souhaitent. \u00bb Quand je me suis demand\u00e9 ce qui repr\u00e9sentait quelque chose qui est \u00ab toujours l\u00e0 \u00bb, la r\u00e9ponse a \u00e9t\u00e9 le soleil. Nous voulons \u00eatre comme le soleil pour quelqu\u2019un \u2014 une pr\u00e9sence qui apporte lumi\u00e8re et \u00e9nergie. Et quand on est sur sc\u00e8ne, on est toutes invincibles \u2014 j\u2019adore cette aura qui nous entoure dans ces moments-l\u00e0. Alors je nous ai imagin\u00e9s comme des super-h\u00e9ros et j\u2019ai \u00e9crit cette chanson avec le message : \u00ab On sera toujours l\u00e0 \u2014 on est vos super-h\u00e9ros. \u00bb<\/p>\n\n\n\n<p><strong>\u25a0<\/strong> <strong>La phrase \u00ab M\u00eame si tu tombes dans les t\u00e9n\u00e8bres \u00bb vient donc de cette id\u00e9e ?<br>Saiki<\/strong> : Exactement. \u00c7a veut dire : \u00ab M\u00eame si tu tombes dans les t\u00e9n\u00e8bres, on te remontera \u2014 laisse-nous faire ! \u00bb \u00c7a a donn\u00e9 des paroles assez fortes et pleines d\u2019assurance.<\/p>\n\n\n\n<p><strong>\u25a0<\/strong> <strong>Kobato-san crie vraiment beaucoup sur ce morceau.<br>Miku Kobato<\/strong> : Oui-po, on m\u2019a demand\u00e9 de crier beaucoup-po. Saiki m\u2019a demand\u00e9 d\u2019essayer un nouveau type de partie improvis\u00e9e ou de refrain-po. D\u2019habitude, on enregistre d\u2019abord la voix principale, puis les ch\u0153urs, mais cette fois-ci, je me suis adapt\u00e9e au style de chant de Saiki et j\u2019ai cri\u00e9 une phrase enti\u00e8re en anglais juste avant le refrain-po. Pendant l\u2019enregistrement, j\u2019ai imagin\u00e9 diff\u00e9rents personnages et j\u2019ai essay\u00e9 plusieurs intonations, donc \u00e7a a \u00e9t\u00e9 un vrai d\u00e9fi pour moi-po. Le tempo est rapide, et comme je joue aussi de la guitare sans m&rsquo;arr\u00eater-po, je pense que c&rsquo;est le morceau le plus intense pour moi lors des Okyujis parmi les nouveaux-po (rires). <\/p>\n\n\n\n<p><strong>\u25a0<\/strong> <strong>Le groove d\u00e8s le d\u00e9but est g\u00e9nial. MISA, comment s&rsquo;est pass\u00e9 l&rsquo;arrangement de la basse ?<\/strong><br><strong>MISA<\/strong> : Oui, il y a beaucoup de mouvement d\u00e8s l&rsquo;intro. Pour le refrain, je voulais que la basse apporte aussi une touche m\u00e9lodique. Pour le solo, je voulais qu\u2019il sonne comme en live \u2014 plein d\u2019une \u00e9nergie brute \u2014 alors, dans cette courte section de solo, j\u2019ai m\u00e9lang\u00e9 des accords, du slap et d\u2019autres techniques pour lui donner une sonorit\u00e9 riche et satisfaisante. \u00c7a m\u2019a pris un peu de temps pour le peaufiner. Quant au th\u00e8me de \u00ab SUPER SUNSHINE \u00bb \u2014 peut-\u00eatre que \u00e7a ne transpara\u00eet pas facilement \u00e0 cause de ma personnalit\u00e9 \u2014 mais j\u2019aime vraiment tout le monde profond\u00e9ment et je veux toujours rendre les gens heureux, tout comme la chanson.<br><strong>Akane<\/strong> : Je partage ce sentiment. C&rsquo;est gr\u00e2ce \u00e0 vous tous que je peux jouer de la batterie avec le sourire et profiter pleinement du concert. Je joue toujours dans l&rsquo;espoir de vous transmettre \u00e0 mon tour cette \u00e9nergie. Pour ce morceau, j&rsquo;ai enregistr\u00e9 la batterie en gardant \u00e0 l&rsquo;esprit cette ambiance de concert. En fait, l&rsquo;enregistrement de la batterie a commenc\u00e9 il y a deux ans, juste au moment o\u00f9 nous \u00e9tions en tourn\u00e9e pour notre 10e anniversaire, et je pense que ces \u00e9motions se sont refl\u00e9t\u00e9es dans le son. Je crois que c&rsquo;est pour cela que le son de la batterie est si \u00e9clatant. De plus, les paroles de SAIKI sont simples mais percutantes : directes et chaleureuses.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"78\" src=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg\" alt=\"\" class=\"wp-image-8482\" srcset=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg 1024w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-300x23.jpg 300w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-advgb-columns advgb-columns-wrapper\" id=\"advgb-cols-f09b774a-9b37-4ccb-91e5-53f4cce9fb87\"><div class=\"advgb-columns-container\"><div class=\"advgb-columns advgb-columns-row advgb-is-mobile advgb-columns-2 layout-12-12 mbl-layout-stacked vgutter-10\">\n<div class=\"wp-block-advgb-column advgb-column\" id=\"advgb-col-f05156f2-06f6-42da-8510-34f91e1d45f1\"><div class=\"advgb-column-inner\" style=\"border-style:none;border-width:1px\">\n<div class=\"wp-block-advgb-button alignnone\"><a class=\"wp-block-advgb-button_link advgbbtn-aa6d940c-666c-4e21-b3b9-2df0e38cec84\" href=\"https:\/\/www.band-maid.fr\/index.php\/scooooop\/\" target=\"_self\" rel=\"noopener noreferrer\"><span>SCOOOOOP<\/span><\/a><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-advgb-column advgb-column\" id=\"advgb-col-2c116527-87b0-45a4-bf7e-e76419eff94c\"><div class=\"advgb-column-inner\" style=\"border-style:none;border-width:1px\">\n<div class=\"wp-block-advgb-button alignnone\"><a class=\"wp-block-advgb-button_link advgbbtn-89a91e3e-a078-4125-8237-7731de0c1517\" href=\"https:\/\/www.band-maid.fr\/index.php\/discographie-de-band-maid\/\" target=\"_self\" rel=\"noopener noreferrer\"><span>Discographie<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"78\" src=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg\" alt=\"\" class=\"wp-image-8482\" srcset=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg 1024w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-300x23.jpg 300w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"765\" height=\"1024\" src=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/04-Super-Sunshine3-1-765x1024.jpg\" alt=\"\" class=\"wp-image-8495\" srcset=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/04-Super-Sunshine3-1-765x1024.jpg 765w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/04-Super-Sunshine3-1-224x300.jpg 224w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/04-Super-Sunshine3-1.jpg 897w\" sizes=\"(max-width: 765px) 100vw, 765px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"78\" src=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg\" alt=\"\" class=\"wp-image-8482\" srcset=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-1024x78.jpg 1024w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire-300x23.jpg 300w, https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/02\/bande-noire.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<style class=\"advgb-styles-renderer\">#advgb-col-32f567f2-7baa-4d81-a6db-f2c96cb0bbfc>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-32f567f2-7baa-4d81-a6db-f2c96cb0bbfc>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-32f567f2-7baa-4d81-a6db-f2c96cb0bbfc>.advgb-column-inner{}}#advgb-col-7badd8ee-f522-410c-b200-a6d87093428e>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-7badd8ee-f522-410c-b200-a6d87093428e>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-7badd8ee-f522-410c-b200-a6d87093428e>.advgb-column-inner{}}#advgb-col-d335750b-ba7d-4700-b605-fae16f5032b1>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-d335750b-ba7d-4700-b605-fae16f5032b1>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-d335750b-ba7d-4700-b605-fae16f5032b1>.advgb-column-inner{}}#advgb-cols-1a8e2492-aab6-4967-9513-e620fee8f661{}@media screen and (max-width: 1023px) {#advgb-cols-1a8e2492-aab6-4967-9513-e620fee8f661{}}@media screen and (max-width: 767px) {#advgb-cols-1a8e2492-aab6-4967-9513-e620fee8f661{}}#advgb-col-32f567f2-7baa-4d81-a6db-f2c96cb0bbfc>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-32f567f2-7baa-4d81-a6db-f2c96cb0bbfc>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-32f567f2-7baa-4d81-a6db-f2c96cb0bbfc>.advgb-column-inner{}}#advgb-col-7badd8ee-f522-410c-b200-a6d87093428e>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-7badd8ee-f522-410c-b200-a6d87093428e>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-7badd8ee-f522-410c-b200-a6d87093428e>.advgb-column-inner{}}#advgb-col-d335750b-ba7d-4700-b605-fae16f5032b1>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-d335750b-ba7d-4700-b605-fae16f5032b1>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-d335750b-ba7d-4700-b605-fae16f5032b1>.advgb-column-inner{}}.advgbbtn-aa6d940c-666c-4e21-b3b9-2df0e38cec84{font-size:18px;color:#fff !important;background-color:#2196f3 !important;margin:0px 0px 0px 0px !important;padding:10px 30px 10px 30px;border-width:1px !important;border-style:none;border-radius:50px !important;}.advgbbtn-aa6d940c-666c-4e21-b3b9-2df0e38cec84:hover{box-shadow:1px 1px 12px 0px #ccc;opacity:1;transition:all 0.2s ease;}.advgbbtn-aa6d940c-666c-4e21-b3b9-2df0e38cec84 > i {display: none !important;}#advgb-col-f05156f2-06f6-42da-8510-34f91e1d45f1>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-f05156f2-06f6-42da-8510-34f91e1d45f1>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-f05156f2-06f6-42da-8510-34f91e1d45f1>.advgb-column-inner{}}.advgbbtn-aa6d940c-666c-4e21-b3b9-2df0e38cec84{font-size:18px;color:#fff !important;background-color:#2196f3 !important;margin:0px 0px 0px 0px !important;padding:10px 30px 10px 30px;border-width:1px !important;border-style:none;border-radius:50px !important;}.advgbbtn-aa6d940c-666c-4e21-b3b9-2df0e38cec84:hover{box-shadow:1px 1px 12px 0px #ccc;opacity:1;transition:all 0.2s ease;}.advgbbtn-aa6d940c-666c-4e21-b3b9-2df0e38cec84 > i {display: none !important;}.advgbbtn-89a91e3e-a078-4125-8237-7731de0c1517{font-size:18px;color:#fff !important;background-color:#2196f3 !important;margin:0px 0px 0px 0px !important;padding:10px 30px 10px 30px;border-width:1px !important;border-style:none;border-radius:50px !important;}.advgbbtn-89a91e3e-a078-4125-8237-7731de0c1517:hover{box-shadow:1px 1px 12px 0px #ccc;opacity:1;transition:all 0.2s ease;}.advgbbtn-89a91e3e-a078-4125-8237-7731de0c1517 > i {display: none !important;}#advgb-col-2c116527-87b0-45a4-bf7e-e76419eff94c>.advgb-column-inner{text-align:right;}@media screen and (max-width: 1023px) {#advgb-col-2c116527-87b0-45a4-bf7e-e76419eff94c>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-2c116527-87b0-45a4-bf7e-e76419eff94c>.advgb-column-inner{}}.advgbbtn-89a91e3e-a078-4125-8237-7731de0c1517{font-size:18px;color:#fff !important;background-color:#2196f3 !important;margin:0px 0px 0px 0px !important;padding:10px 30px 10px 30px;border-width:1px !important;border-style:none;border-radius:50px !important;}.advgbbtn-89a91e3e-a078-4125-8237-7731de0c1517:hover{box-shadow:1px 1px 12px 0px #ccc;opacity:1;transition:all 0.2s ease;}.advgbbtn-89a91e3e-a078-4125-8237-7731de0c1517 > i {display: none !important;}#advgb-cols-f09b774a-9b37-4ccb-91e5-53f4cce9fb87{}@media screen and (max-width: 1023px) {#advgb-cols-f09b774a-9b37-4ccb-91e5-53f4cce9fb87{}}@media screen and (max-width: 767px) {#advgb-cols-f09b774a-9b37-4ccb-91e5-53f4cce9fb87{}}#advgb-col-f05156f2-06f6-42da-8510-34f91e1d45f1>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-f05156f2-06f6-42da-8510-34f91e1d45f1>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-f05156f2-06f6-42da-8510-34f91e1d45f1>.advgb-column-inner{}}.advgbbtn-aa6d940c-666c-4e21-b3b9-2df0e38cec84{font-size:18px;color:#fff !important;background-color:#2196f3 !important;margin:0px 0px 0px 0px !important;padding:10px 30px 10px 30px;border-width:1px !important;border-style:none;border-radius:50px !important;}.advgbbtn-aa6d940c-666c-4e21-b3b9-2df0e38cec84:hover{box-shadow:1px 1px 12px 0px #ccc;opacity:1;transition:all 0.2s ease;}.advgbbtn-aa6d940c-666c-4e21-b3b9-2df0e38cec84 > i {display: none !important;}#advgb-col-2c116527-87b0-45a4-bf7e-e76419eff94c>.advgb-column-inner{text-align:right;}@media screen and (max-width: 1023px) {#advgb-col-2c116527-87b0-45a4-bf7e-e76419eff94c>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-2c116527-87b0-45a4-bf7e-e76419eff94c>.advgb-column-inner{}}.advgbbtn-89a91e3e-a078-4125-8237-7731de0c1517{font-size:18px;color:#fff !important;background-color:#2196f3 !important;margin:0px 0px 0px 0px !important;padding:10px 30px 10px 30px;border-width:1px !important;border-style:none;border-radius:50px !important;}.advgbbtn-89a91e3e-a078-4125-8237-7731de0c1517:hover{box-shadow:1px 1px 12px 0px #ccc;opacity:1;transition:all 0.2s ease;}.advgbbtn-89a91e3e-a078-4125-8237-7731de0c1517 > i {display: none !important;}<\/style>","protected":false},"excerpt":{"rendered":"<p>SUPER SUNSHINE [Verse 1]I wanna dive\u66d6\u6627\u306a\u672a\u6765\u3000\u585e\u3050\u4e16\u754c\u3000\u8ced\u3051\u308b\u52c7\u6c17\u3092\u304f\u308c\u7b54\u3048\u306a\u3093\u3066\u3000\u306f\u3058\u3081\u304b\u3089\u8981\u3089\u306a\u3044I wanna change your mind\u60a9\u3093\u3060\u65e5\u3005\u3060\u3063\u3066\u3000\u304d\u3063\u3068\u7ce7\u306b\u306a\u308b\u304b\u3089\u8e0f\u307f\u51fa\u3059\u3093\u3060 the time has come [Pre-Chorus]Give it a try try\u3000\u3053\u306e\u307e\u307e\u3058\u3083\u307e\u3060Fight for your pride pride\u7d42\u308f\u308c\u306a\u3044\u3088\u971e\u3080\u660e\u65e5\u306b\u602f\u3048\u306a\u3044\u4eca\u3092\u751f\u304d\u3066\u307f\u305b\u308b(Run into the light) [Chorus]I will get to it\u8ff7\u3063\u3066\u3082\u69cb\u308f\u306a\u3044Don&rsquo;t miss it\u3000\u9032\u3081\u3053\u306e\u624b\u306b\u63b4\u307f\u53d6\u308b\u3088\u4e16\u754c\u3092\u5909\u3048\u308bSUPER SUNSHINE [Verse 2]No looking back\u99c6\u3051\u629c\u3051\u3066\u3044\u304f\u4e0d\u5b89\u3060\u3063\u3066\u80cc\u8ca0\u3063\u3066\u751f\u304d\u308b\u3060\u3051\u3055\u4fe1\u3058\u305f\u9053Let&rsquo;s roll it [Pre-Chorus]Rat-a-tat-tat-tat\u97f3\u306b\u5408\u308f\u305b\u3066Rat-a-tat-tat-tat-tat\u523b\u3081\u53eb\u3076\u3053\u306e\u58f0\u306f\u6d88\u3048\u306a\u3044\u4e8c\u5ea6\u3068\u632f\u308a\u5411\u304b\u306a\u3044\u3088(Through the night, I&rsquo;ll follow my own way) [Chorus]I will never die\u8fbf\u308a\u7740\u304f\u65e5\u307e\u3067Don&rsquo;t let go\u3000\u9032\u3081\u6d41\u3057\u305f\u6d99\u3055\u3048\u3082\u7121\u99c4\u306b\u3057\u306a\u3044SUPER SUNSHINE &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.band-maid.fr\/index.php\/super-sunshine-super-soleil\/\" class=\"more-link\">Lire la suite de<span class=\"screen-reader-text\">\u00ab\u00a0SUPER SUNSHINE\u00a0\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":8968,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"class_list":["post-8486","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SUPER SUNSHINE - BAND-MAID<\/title>\n<meta name=\"description\" content=\"Traduction non officielle des paroles de Super Sunshine Paroles \u00e9crites par Miku Musique et arrangements : BAND-MAID\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.band-maid.fr\/index.php\/super-sunshine-super-soleil\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SUPER SUNSHINE - BAND-MAID\" \/>\n<meta property=\"og:description\" content=\"Traduction non officielle des paroles de Super Sunshine Paroles \u00e9crites par Miku Musique et arrangements : BAND-MAID\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.band-maid.fr\/index.php\/super-sunshine-super-soleil\/\" \/>\n<meta property=\"og:site_name\" content=\"BAND-MAID\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bandmaid\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-03T11:09:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/03\/Bandeau-SCOOOOOP.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@bandmaid\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/index.php\\\/super-sunshine-super-soleil\\\/\",\"url\":\"https:\\\/\\\/www.band-maid.fr\\\/index.php\\\/super-sunshine-super-soleil\\\/\",\"name\":\"SUPER SUNSHINE - BAND-MAID\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/index.php\\\/super-sunshine-super-soleil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/index.php\\\/super-sunshine-super-soleil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.band-maid.fr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Bandeau-SCOOOOOP.jpg\",\"datePublished\":\"2026-02-05T21:54:53+00:00\",\"dateModified\":\"2026-05-03T11:09:32+00:00\",\"description\":\"Traduction non officielle des paroles de Super Sunshine Paroles \u00e9crites par Miku Musique et arrangements : BAND-MAID\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/index.php\\\/super-sunshine-super-soleil\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.band-maid.fr\\\/index.php\\\/super-sunshine-super-soleil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/index.php\\\/super-sunshine-super-soleil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.band-maid.fr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Bandeau-SCOOOOOP.jpg\",\"contentUrl\":\"https:\\\/\\\/www.band-maid.fr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Bandeau-SCOOOOOP.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/index.php\\\/super-sunshine-super-soleil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.band-maid.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SUPER SUNSHINE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.band-maid.fr\\\/\",\"name\":\"BAND-MAID\",\"description\":\"WORLD DOMINATION\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.band-maid.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/#organization\",\"name\":\"BAND-MAID\",\"url\":\"https:\\\/\\\/www.band-maid.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/wglgkdc.cluster121.hosting.ovh.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logo_band-maid_b.png\",\"contentUrl\":\"http:\\\/\\\/wglgkdc.cluster121.hosting.ovh.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logo_band-maid_b.png\",\"width\":540,\"height\":93,\"caption\":\"BAND-MAID\"},\"image\":{\"@id\":\"https:\\\/\\\/www.band-maid.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/bandmaid\",\"https:\\\/\\\/x.com\\\/bandmaid\",\"https:\\\/\\\/www.instagram.com\\\/bandmaid.jp\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCJToUvYrmkmTCR-bluEaQfA\",\"https:\\\/\\\/www.tiktok.com\\\/@bandmaid_int\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SUPER SUNSHINE - BAND-MAID","description":"Traduction non officielle des paroles de Super Sunshine Paroles \u00e9crites par Miku Musique et arrangements : BAND-MAID","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.band-maid.fr\/index.php\/super-sunshine-super-soleil\/","og_locale":"fr_FR","og_type":"article","og_title":"SUPER SUNSHINE - BAND-MAID","og_description":"Traduction non officielle des paroles de Super Sunshine Paroles \u00e9crites par Miku Musique et arrangements : BAND-MAID","og_url":"https:\/\/www.band-maid.fr\/index.php\/super-sunshine-super-soleil\/","og_site_name":"BAND-MAID","article_publisher":"https:\/\/www.facebook.com\/bandmaid","article_modified_time":"2026-05-03T11:09:32+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/03\/Bandeau-SCOOOOOP.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@bandmaid","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.band-maid.fr\/index.php\/super-sunshine-super-soleil\/","url":"https:\/\/www.band-maid.fr\/index.php\/super-sunshine-super-soleil\/","name":"SUPER SUNSHINE - BAND-MAID","isPartOf":{"@id":"https:\/\/www.band-maid.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.band-maid.fr\/index.php\/super-sunshine-super-soleil\/#primaryimage"},"image":{"@id":"https:\/\/www.band-maid.fr\/index.php\/super-sunshine-super-soleil\/#primaryimage"},"thumbnailUrl":"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/03\/Bandeau-SCOOOOOP.jpg","datePublished":"2026-02-05T21:54:53+00:00","dateModified":"2026-05-03T11:09:32+00:00","description":"Traduction non officielle des paroles de Super Sunshine Paroles \u00e9crites par Miku Musique et arrangements : BAND-MAID","breadcrumb":{"@id":"https:\/\/www.band-maid.fr\/index.php\/super-sunshine-super-soleil\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.band-maid.fr\/index.php\/super-sunshine-super-soleil\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.band-maid.fr\/index.php\/super-sunshine-super-soleil\/#primaryimage","url":"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/03\/Bandeau-SCOOOOOP.jpg","contentUrl":"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/03\/Bandeau-SCOOOOOP.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.band-maid.fr\/index.php\/super-sunshine-super-soleil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.band-maid.fr\/"},{"@type":"ListItem","position":2,"name":"SUPER SUNSHINE"}]},{"@type":"WebSite","@id":"https:\/\/www.band-maid.fr\/#website","url":"https:\/\/www.band-maid.fr\/","name":"BAND-MAID","description":"WORLD DOMINATION","publisher":{"@id":"https:\/\/www.band-maid.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.band-maid.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.band-maid.fr\/#organization","name":"BAND-MAID","url":"https:\/\/www.band-maid.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.band-maid.fr\/#\/schema\/logo\/image\/","url":"http:\/\/wglgkdc.cluster121.hosting.ovh.net\/wp-content\/uploads\/2026\/01\/logo_band-maid_b.png","contentUrl":"http:\/\/wglgkdc.cluster121.hosting.ovh.net\/wp-content\/uploads\/2026\/01\/logo_band-maid_b.png","width":540,"height":93,"caption":"BAND-MAID"},"image":{"@id":"https:\/\/www.band-maid.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bandmaid","https:\/\/x.com\/bandmaid","https:\/\/www.instagram.com\/bandmaid.jp\/","https:\/\/www.youtube.com\/channel\/UCJToUvYrmkmTCR-bluEaQfA","https:\/\/www.tiktok.com\/@bandmaid_int"]}]}},"coauthors":[],"author_meta":{"author_link":"https:\/\/www.band-maid.fr\/index.php\/author\/admin8693\/","display_name":"LJB"},"relative_dates":{"created":"Publi\u00e9 3 mois il y a","modified":"Mis \u00e0 jour 1 semaine il y a"},"absolute_dates":{"created":"Publi\u00e9 le 05\/02\/2026","modified":"Mise \u00e0 jour le 03\/05\/2026"},"absolute_dates_time":{"created":"Publi\u00e9 le 05\/02\/2026 21h54","modified":"Mise \u00e0 jour le 03\/05\/2026 11h09"},"featured_img_caption":"","featured_img":"https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/03\/Bandeau-SCOOOOOP.jpg","series_order":"","featured_media_urls":{"thumbnail":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/03\/Bandeau-SCOOOOOP-150x150.jpg",150,150,true],"medium":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/03\/Bandeau-SCOOOOOP-300x300.jpg",300,300,true],"medium_large":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/03\/Bandeau-SCOOOOOP.jpg",768,768,false],"large":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/03\/Bandeau-SCOOOOOP-1024x1024.jpg",950,950,true],"1536x1536":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/03\/Bandeau-SCOOOOOP.jpg",1200,1200,false],"2048x2048":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/03\/Bandeau-SCOOOOOP.jpg",1200,1200,false],"inspiro-featured-image":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/03\/Bandeau-SCOOOOOP.jpg",1200,1200,false],"inspiro-loop":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/03\/Bandeau-SCOOOOOP-950x320.jpg",950,320,true],"inspiro-loop@2x":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/03\/Bandeau-SCOOOOOP-1200x640.jpg",1200,640,true],"portfolio_item-thumbnail":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/03\/Bandeau-SCOOOOOP-600x400.jpg",600,400,true],"portfolio_item-thumbnail@2x":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/03\/Bandeau-SCOOOOOP-1200x800.jpg",1200,800,true],"portfolio_item-masonry":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/03\/Bandeau-SCOOOOOP-600x600.jpg",600,600,true],"portfolio_item-masonry@2x":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/03\/Bandeau-SCOOOOOP.jpg",1200,1200,false],"portfolio_item-thumbnail_cinema":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/03\/Bandeau-SCOOOOOP-800x335.jpg",800,335,true],"portfolio_item-thumbnail_portrait":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/03\/Bandeau-SCOOOOOP-600x900.jpg",600,900,true],"portfolio_item-thumbnail_portrait@2x":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/03\/Bandeau-SCOOOOOP.jpg",1200,1200,false],"portfolio_item-thumbnail_square":["https:\/\/www.band-maid.fr\/wp-content\/uploads\/2026\/03\/Bandeau-SCOOOOOP-800x800.jpg",800,800,true]},"_links":{"self":[{"href":"https:\/\/www.band-maid.fr\/index.php\/wp-json\/wp\/v2\/pages\/8486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.band-maid.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.band-maid.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.band-maid.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.band-maid.fr\/index.php\/wp-json\/wp\/v2\/comments?post=8486"}],"version-history":[{"count":14,"href":"https:\/\/www.band-maid.fr\/index.php\/wp-json\/wp\/v2\/pages\/8486\/revisions"}],"predecessor-version":[{"id":10609,"href":"https:\/\/www.band-maid.fr\/index.php\/wp-json\/wp\/v2\/pages\/8486\/revisions\/10609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.band-maid.fr\/index.php\/wp-json\/wp\/v2\/media\/8968"}],"wp:attachment":[{"href":"https:\/\/www.band-maid.fr\/index.php\/wp-json\/wp\/v2\/media?parent=8486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}